{"id":47549,"date":"2024-10-15T11:47:37","date_gmt":"2024-10-15T09:47:37","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?p=47549"},"modified":"2024-10-15T16:23:15","modified_gmt":"2024-10-15T14:23:15","slug":"estrena-de-loneliness-de-roberto-g-alonso-al-tnc","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/","title":{"rendered":"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso"},"content":{"rendered":"<p><\/p>\n<h4><strong>La companyia de dansa convida a reflexionar sobre l\u2019assetjament verbal, f\u00edsic i virtual entre els adolescents.<\/strong><\/h4>\n<p><em>Loneliness <\/em>\u00e9s una obra amb dramat\u00fargia, direcci\u00f3 i coregorafia de Roberto G. Alonso\u00a0que interpel\u00b7la directament el p\u00fablic adolescent. A partir de la dansa i del\u00a0teatre f\u00edsic, l&#8217;espectacle reflexiona\u00a0sobre el <em>bullying <\/em>i\u00a0el fet de mirar cap a una altra banda davant qualsevol tipus de viol\u00e8ncia.<\/p>\n<p><span style=\"font-weight: 400;\">Per a Alonso, \u201c<\/span><em><span style=\"font-weight: 400;\">Loneliness<\/span><span style=\"font-weight: 400;\"> neix de la necessitat de tancar ferides i de la voluntat de confrontar-nos amb una realitat inc\u00f2moda i alhora inq\u00fcestionable, <\/span><span style=\"font-weight: 400;\">el bullying<\/span><\/em><span style=\"font-weight: 400;\"><em>. Vol ser un recordatori a la nostra responsabilitat, una crida a no mirar cap a una altra banda davant d\u2019un fenomen tan present i devastador, un crit en contra de la viol\u00e8ncia f\u00edsica i psicol\u00f2gica<\/em>\u201d.<\/span><\/p>\n<p>L&#8217;obra s&#8217;estrenar\u00e0 al TNC i es podr\u00e0 veure del 16 al 27 d&#8217;octubre a la Sala Tallers.\u00a0Les funcions dels dimecres 16 i 17 d&#8217;octubre seran matinals, per a centres educatius, i la resta de dies la funci\u00f3 ser\u00e0 en l&#8217;horari de tarda habitual (de dimecres a dissabte a les 19h i diumenge a les 18h).<\/p>\n<p>Moviment, teatre f\u00edsic i videocreaci\u00f3 s\u2019uneixen en aquesta proposta que explora la conducta humana de l\u2019exclusi\u00f3 del diferent, on el patiment ali\u00e8, l\u2019escarni i l\u2019enfonsament moral de l\u2019individu esdevenen un cruel joc de poder. Un comprom\u00e8s al\u00b7legat en contra de tots els tipus de viol\u00e8ncia i del fet de mirar cap a una altra banda davant un fenomen molt vigent als instituts, el <em>bullying<\/em>.<\/p>\n<p><span style=\"font-weight: 400;\">No us perdeu <\/span><span style=\"font-weight: 400;\">Loneliness <\/span><span style=\"font-weight: 400;\">al TNC<\/span><span style=\"font-weight: 400;\">, <\/span><span style=\"font-weight: 400;\">un al\u00b7legat comprom\u00e8s en contra de tots els tipus de viol\u00e8ncia i del fet de mirar cap a una altra banda davant un fenomen tant vigent als instituts com el\u00a0<em>bulling.<\/em><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>La companyia de dansa convida a reflexionar sobre l\u2019assetjament verbal, f\u00edsic i virtual entre els adolescents. Loneliness \u00e9s una obra&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/\">M\u00e9s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":47552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3600,3560],"tags":[2488,998,3106],"class_list":["post-47549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dansa","category-teatre","tag-dansa","tag-teatre","tag-teatre-nacional-de-catalunya"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso  &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso  &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"La companyia de dansa convida a reflexionar sobre l\u2019assetjament verbal, f\u00edsic i virtual entre els adolescents. Loneliness \u00e9s una obra... M\u00e9s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T09:47:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T14:23:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2024\/10\/dsc-04830.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso\",\"datePublished\":\"2024-10-15T09:47:37+00:00\",\"dateModified\":\"2024-10-15T14:23:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/\"},\"wordCount\":558,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/10\\\/25080243\\\/dsc-04830.jpg\",\"keywords\":[\"dansa\",\"teatre\",\"Teatre Nacional de Catalunya\"],\"articleSection\":[\"Dansa\",\"Teatre\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/\",\"name\":\"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso  &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/10\\\/25080243\\\/dsc-04830.jpg\",\"datePublished\":\"2024-10-15T09:47:37+00:00\",\"dateModified\":\"2024-10-15T14:23:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/10\\\/25080243\\\/dsc-04830.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/10\\\/25080243\\\/dsc-04830.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunitat Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso  &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/","og_locale":"ca_ES","og_type":"article","og_title":"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso  &#8211; Poblenou Urban District","og_description":"La companyia de dansa convida a reflexionar sobre l\u2019assetjament verbal, f\u00edsic i virtual entre els adolescents. Loneliness \u00e9s una obra... M\u00e9s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/","og_site_name":"Poblenou Urban District","article_published_time":"2024-10-15T09:47:37+00:00","article_modified_time":"2024-10-15T14:23:15+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2024\/10\/dsc-04830.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"pnud","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso","datePublished":"2024-10-15T09:47:37+00:00","dateModified":"2024-10-15T14:23:15+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/"},"wordCount":558,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/10\/25080243\/dsc-04830.jpg","keywords":["dansa","teatre","Teatre Nacional de Catalunya"],"articleSection":["Dansa","Teatre"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/","url":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/","name":"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso  &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/10\/25080243\/dsc-04830.jpg","datePublished":"2024-10-15T09:47:37+00:00","dateModified":"2024-10-15T14:23:15+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/"]]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2024\/10\/25080243\/dsc-04830.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/10\/25080243\/dsc-04830.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/ca\/estrena-de-loneliness-de-roberto-g-alonso-al-tnc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/ca\/"},{"@type":"ListItem","position":2,"name":"El TNC estrena Loneliness de la companyia de dansa Roberto G. Alonso"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website","url":"https:\/\/poblenouurbandistrict.com\/ca\/","name":"Poblenou Urban District","description":"Comunitat Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/47549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/comments?post=47549"}],"version-history":[{"count":4,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/47549\/revisions"}],"predecessor-version":[{"id":47588,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/47549\/revisions\/47588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media\/47552"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media?parent=47549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/categories?post=47549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tags?post=47549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}