{"id":6303,"date":"2015-06-15T10:52:59","date_gmt":"2015-06-15T08:52:59","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=6303"},"modified":"2023-06-23T10:51:05","modified_gmt":"2023-06-23T08:51:05","slug":"venda-especial-de-pintures-de-perico-pastor","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/","title":{"rendered":"Venta especial de pinturas de Perico Pastor"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6303\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Castellano\">Castellano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en Castellano.<\/p>\n","protected":false},"author":5,"featured_media":6304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[314,719,1455,512,979],"class_list":["post-6303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-arte","tag-ilustracion","tag-perico-pastor","tag-pintura","tag-venta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venda especial de pintures de Perico Pastor<\/title>\n<meta name=\"description\" content=\"Dilluns 15 de juny \u00e9s el darrer dia per adquirir una de les dotze obres que Perico Pastor posa a la venta amb un descompte extraordinari\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venda especial de pintures de Perico Pastor\" \/>\n<meta property=\"og:description\" content=\"Dilluns 15 de juny \u00e9s el darrer dia per adquirir una de les dotze obres que Perico Pastor posa a la venta amb un descompte extraordinari\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-15T08:52:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-23T08:51:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/06\/WLS-14.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/venda-especial-de-pintures-de-perico-pastor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/venda-especial-de-pintures-de-perico-pastor\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"Venta especial de pinturas de Perico Pastor\",\"datePublished\":\"2015-06-15T08:52:59+00:00\",\"dateModified\":\"2023-06-23T08:51:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/venda-especial-de-pintures-de-perico-pastor\\\/\"},\"wordCount\":613,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/venda-especial-de-pintures-de-perico-pastor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/06\\\/25010424\\\/WLS-14.jpeg\",\"keywords\":[\"Arte\",\"ilustraci\u00f3n\",\"perico pastor\",\"pintura\",\"venta\"],\"articleSection\":[\"Est\u00e0 passant\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/\",\"name\":\"Venda especial de pintures de Perico Pastor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/venda-especial-de-pintures-de-perico-pastor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/06\\\/25010424\\\/WLS-14.jpeg\",\"datePublished\":\"2015-06-15T08:52:59+00:00\",\"dateModified\":\"2023-06-23T08:51:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"Dilluns 15 de juny \u00e9s el darrer dia per adquirir una de les dotze obres que Perico Pastor posa a la venta amb un descompte extraordinari\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/06\\\/25010424\\\/WLS-14.jpeg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/06\\\/25010424\\\/WLS-14.jpeg\",\"width\":1280,\"height\":608,\"caption\":\"WLS 14\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/venda-especial-de-pintures-de-perico-pastor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venta especial de pinturas de Perico Pastor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunitat Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venda especial de pintures de Perico Pastor","description":"Dilluns 15 de juny \u00e9s el darrer dia per adquirir una de les dotze obres que Perico Pastor posa a la venta amb un descompte extraordinari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/","og_locale":"ca_ES","og_type":"article","og_title":"Venda especial de pintures de Perico Pastor","og_description":"Dilluns 15 de juny \u00e9s el darrer dia per adquirir una de les dotze obres que Perico Pastor posa a la venta amb un descompte extraordinari","og_url":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-06-15T08:52:59+00:00","article_modified_time":"2023-06-23T08:51:05+00:00","og_image":[{"width":1280,"height":608,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/06\/WLS-14.jpeg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"pnud","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/venda-especial-de-pintures-de-perico-pastor\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/venda-especial-de-pintures-de-perico-pastor\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"Venta especial de pinturas de Perico Pastor","datePublished":"2015-06-15T08:52:59+00:00","dateModified":"2023-06-23T08:51:05+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/venda-especial-de-pintures-de-perico-pastor\/"},"wordCount":613,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/venda-especial-de-pintures-de-perico-pastor\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/06\/25010424\/WLS-14.jpeg","keywords":["Arte","ilustraci\u00f3n","perico pastor","pintura","venta"],"articleSection":["Est\u00e0 passant"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/","url":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/","name":"Venda especial de pintures de Perico Pastor","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/venda-especial-de-pintures-de-perico-pastor\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/06\/25010424\/WLS-14.jpeg","datePublished":"2015-06-15T08:52:59+00:00","dateModified":"2023-06-23T08:51:05+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"Dilluns 15 de juny \u00e9s el darrer dia per adquirir una de les dotze obres que Perico Pastor posa a la venta amb un descompte extraordinari","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/"]]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2015\/06\/25010424\/WLS-14.jpeg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/06\/25010424\/WLS-14.jpeg","width":1280,"height":608,"caption":"WLS 14"},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/ca\/venda-especial-de-pintures-de-perico-pastor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Venta especial de pinturas de Perico Pastor"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website","url":"https:\/\/poblenouurbandistrict.com\/ca\/","name":"Poblenou Urban District","description":"Comunitat Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/6303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/comments?post=6303"}],"version-history":[{"count":3,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/6303\/revisions"}],"predecessor-version":[{"id":40031,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/6303\/revisions\/40031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media\/6304"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media?parent=6303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/categories?post=6303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tags?post=6303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}