{"id":6924,"date":"2015-10-15T13:37:50","date_gmt":"2015-10-15T11:37:50","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/es\/?p=6924"},"modified":"2015-10-15T13:37:50","modified_gmt":"2015-10-15T11:37:50","slug":"la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/","title":{"rendered":"La quinta sinfon\u00eda de Beethoven y el chelo de Alisa Weilerstein"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6924\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Castellano\">Castellano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en Castellano.<\/p>\n","protected":false},"author":5,"featured_media":6925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1686,1685,1688,1687,1689,842,870],"class_list":["post-6924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alisa-weilerstein","tag-beethoven","tag-chostakovich","tag-diego-matheuz","tag-joan-magrane","tag-lauditori","tag-musica-clasica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La simfonia de Beethoven i el violoncel d\u2019Alisa Weilerstein<\/title>\n<meta name=\"description\" content=\"La cinquena simfonia de Beethoven es representar\u00e0 a L\u2019Auditori. El violoncel d\u2019Alisa Weilerstein compartir\u00e0 protagonisme amb l&#039;obra del compositor alemany\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La simfonia de Beethoven i el violoncel d\u2019Alisa Weilerstein\" \/>\n<meta property=\"og:description\" content=\"La cinquena simfonia de Beethoven es representar\u00e0 a L\u2019Auditori. El violoncel d\u2019Alisa Weilerstein compartir\u00e0 protagonisme amb l&#039;obra del compositor alemany\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-15T11:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2015\/10\/25011155\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"La quinta sinfon\u00eda de Beethoven y el chelo de Alisa Weilerstein\",\"datePublished\":\"2015-10-15T11:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/\"},\"wordCount\":540,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/10\\\/25011155\\\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg\",\"keywords\":[\"Alisa Weilerstein\",\"beethoven\",\"Chostak\u00f3vich\",\"Diego Matheuz\",\"Joan Magran\u00e9\",\"l'auditori\",\"m\u00fasica cl\u00e1sica\"],\"articleSection\":[\"Est\u00e0 passant\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/\",\"name\":\"La simfonia de Beethoven i el violoncel d\u2019Alisa Weilerstein\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/10\\\/25011155\\\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg\",\"datePublished\":\"2015-10-15T11:37:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"La cinquena simfonia de Beethoven es representar\u00e0 a L\u2019Auditori. El violoncel d\u2019Alisa Weilerstein compartir\u00e0 protagonisme amb l'obra del compositor alemany\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/10\\\/25011155\\\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/10\\\/25011155\\\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg\",\"width\":658,\"height\":325,\"caption\":\"Alisa Weilerstein in motion playing the cello\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La quinta sinfon\u00eda de Beethoven y el chelo de Alisa Weilerstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunitat Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La simfonia de Beethoven i el violoncel d\u2019Alisa Weilerstein","description":"La cinquena simfonia de Beethoven es representar\u00e0 a L\u2019Auditori. El violoncel d\u2019Alisa Weilerstein compartir\u00e0 protagonisme amb l'obra del compositor alemany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/","og_locale":"ca_ES","og_type":"article","og_title":"La simfonia de Beethoven i el violoncel d\u2019Alisa Weilerstein","og_description":"La cinquena simfonia de Beethoven es representar\u00e0 a L\u2019Auditori. El violoncel d\u2019Alisa Weilerstein compartir\u00e0 protagonisme amb l'obra del compositor alemany","og_url":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-10-15T11:37:50+00:00","og_image":[{"width":658,"height":325,"url":"https:\/\/media.poblenouurbandistrict.com\/2015\/10\/25011155\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"pnud","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"La quinta sinfon\u00eda de Beethoven y el chelo de Alisa Weilerstein","datePublished":"2015-10-15T11:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/"},"wordCount":540,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/10\/25011155\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg","keywords":["Alisa Weilerstein","beethoven","Chostak\u00f3vich","Diego Matheuz","Joan Magran\u00e9","l'auditori","m\u00fasica cl\u00e1sica"],"articleSection":["Est\u00e0 passant"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/","url":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/","name":"La simfonia de Beethoven i el violoncel d\u2019Alisa Weilerstein","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/10\/25011155\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg","datePublished":"2015-10-15T11:37:50+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"La cinquena simfonia de Beethoven es representar\u00e0 a L\u2019Auditori. El violoncel d\u2019Alisa Weilerstein compartir\u00e0 protagonisme amb l'obra del compositor alemany","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/"]]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2015\/10\/25011155\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/10\/25011155\/alisa-weilerstein-in-motion-playing-the-cello-658x325.jpg","width":658,"height":325,"caption":"Alisa Weilerstein in motion playing the cello"},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/ca\/la-cinquena-simfonia-de-beethoven-i-el-violoncel-dalisa-weilerstein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/ca\/"},{"@type":"ListItem","position":2,"name":"La quinta sinfon\u00eda de Beethoven y el chelo de Alisa Weilerstein"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website","url":"https:\/\/poblenouurbandistrict.com\/ca\/","name":"Poblenou Urban District","description":"Comunitat Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/6924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/comments?post=6924"}],"version-history":[{"count":1,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/6924\/revisions"}],"predecessor-version":[{"id":6926,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/6924\/revisions\/6926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media\/6925"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media?parent=6924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/categories?post=6924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tags?post=6924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}