{"id":10002445,"date":"2022-02-23T18:11:21","date_gmt":"2022-02-23T17:11:21","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?post_type=tribe_events&#038;p=26546"},"modified":"2022-04-04T13:36:43","modified_gmt":"2022-04-04T11:36:43","slug":"obsolescencia-programada","status":"publish","type":"tribe_events","link":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/","title":{"rendered":"Obsolesc\u00e8ncia programada"},"content":{"rendered":"<p><\/p>\n<div class=\"content-wrapper\">\n<div class=\"content\">\n<p>Una dona, al voltant de la cinquantena, entra en una botiga d\u2019electrodom\u00e8stics, dona una ullada i marxa. La mateixa dona, poc despr\u00e9s, hi torna a entrar, fa una pregunta a la dependenta i marxa. Vivim en el m\u00f3n de l\u2019obsolesc\u00e8ncia programada, quan una rentadora s\u2019espatlla o es fa vella, de seguida la canviem per una de nova. I aix\u00f2 \u00e9s el que pensem que vol fer aquesta dona: comprar una rentadora. Per\u00f2 no, no t\u00e9 cap intenci\u00f3 de comprar res. Llavors, per qu\u00e8 hi torna a entrar una tercera vegada?<\/p>\n<\/div>\n<\/div>\n<div class=\"artistica content-right-wrapper\">Autora<br \/>\nAnna Maria Ricart Codina<br \/>\nDirecci\u00f3<br \/>\nM\u00f2nica Bofill<\/div>\n<div><\/div>\n<div>Dimecres, Dissabtes i Diumenges<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Una dona, al voltant de la cinquantena, entra en una botiga d\u2019electrodom\u00e8stics, dona una ullada i marxa. La mateixa dona,&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/\">M\u00e9s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":26547,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[3549],"class_list":["post-10002445","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-teatro","cat_teatro","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obsolesc\u00e8ncia programada &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obsolesc\u00e8ncia programada &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"Una dona, al voltant de la cinquantena, entra en una botiga d\u2019electrodom\u00e8stics, dona una ullada i marxa. La mateixa dona,... M\u00e9s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T11:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2022\/02\/25044857\/diseno-sin-titulo-10-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/\",\"name\":\"Obsolesc\u00e8ncia programada &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/02\\\/25044857\\\/diseno-sin-titulo-10-2.jpg\",\"datePublished\":\"2022-02-23T17:11:21+00:00\",\"dateModified\":\"2022-04-04T11:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/02\\\/25044857\\\/diseno-sin-titulo-10-2.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/02\\\/25044857\\\/diseno-sin-titulo-10-2.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/obsolescencia-programada\\\/2022-03-24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Obsolesc\u00e8ncia programada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunitat Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obsolesc\u00e8ncia programada &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/","og_locale":"ca_ES","og_type":"article","og_title":"Obsolesc\u00e8ncia programada &#8211; Poblenou Urban District","og_description":"Una dona, al voltant de la cinquantena, entra en una botiga d\u2019electrodom\u00e8stics, dona una ullada i marxa. La mateixa dona,... M\u00e9s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/","og_site_name":"Poblenou Urban District","article_modified_time":"2022-04-04T11:36:43+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/media.poblenouurbandistrict.com\/2022\/02\/25044857\/diseno-sin-titulo-10-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/","url":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/","name":"Obsolesc\u00e8ncia programada &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/02\/25044857\/diseno-sin-titulo-10-2.jpg","datePublished":"2022-02-23T17:11:21+00:00","dateModified":"2022-04-04T11:36:43+00:00","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/"]]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2022\/02\/25044857\/diseno-sin-titulo-10-2.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/02\/25044857\/diseno-sin-titulo-10-2.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/obsolescencia-programada\/2022-03-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/"},{"@type":"ListItem","position":3,"name":"Obsolesc\u00e8ncia programada"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website","url":"https:\/\/poblenouurbandistrict.com\/ca\/","name":"Poblenou Urban District","description":"Comunitat Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events\/10002445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events\/10002445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media\/26547"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media?parent=10002445"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tags?post=10002445"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=10002445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}