{"id":10002650,"date":"2022-03-07T14:03:43","date_gmt":"2022-03-07T13:03:43","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?post_type=tribe_events&#038;p=26812"},"modified":"2022-04-04T13:33:39","modified_gmt":"2022-04-04T11:33:39","slug":"exposicio-latencia-engendrar-un-deseo","status":"publish","type":"tribe_events","link":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/","title":{"rendered":"Exposici\u00f3: Latencia, Engendrar un deseo"},"content":{"rendered":"<p>Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, &#8220;Latencia, Engendrar un deseo&#8221;, amb obres de l&#8217;artista Vilma Di Taranto.<\/p>\n<p>Inauguraci\u00f3 el dijous 17 de mar\u00e7 a les 19\u202fh.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, &#8220;Latencia, Engendrar un deseo&#8221;, amb obres de l&#8217;artista Vilma Di Taranto. Inauguraci\u00f3 el&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/\">M\u00e9s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":26813,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[3553],"class_list":["post-10002650","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-exposicion","cat_exposicion","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3: Latencia, Engendrar un deseo &#8211; Poblenou Urban District<\/title>\n<meta name=\"description\" content=\"Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, &quot;Latencia, Engendrar un deseo&quot;, amb obres de l&#039;artista Vilma Di Taranto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3: Latencia, Engendrar un deseo &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, &quot;Latencia, Engendrar un deseo&quot;, amb obres de l&#039;artista Vilma Di Taranto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T11:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2022\/03\/pud-agenda-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/\",\"name\":\"Exposici\u00f3: Latencia, Engendrar un deseo &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pud-agenda-6.jpg\",\"datePublished\":\"2022-03-07T13:03:43+00:00\",\"dateModified\":\"2022-04-04T11:33:39+00:00\",\"description\":\"Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, \\\"Latencia, Engendrar un deseo\\\", amb obres de l'artista Vilma Di Taranto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/#primaryimage\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pud-agenda-6.jpg\",\"contentUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pud-agenda-6.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-latencia-engendrar-un-deseo\\\/2022-04-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exposici\u00f3: Latencia, Engendrar un deseo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunitat Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3: Latencia, Engendrar un deseo &#8211; Poblenou Urban District","description":"Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, \"Latencia, Engendrar un deseo\", amb obres de l'artista Vilma Di Taranto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/","og_locale":"ca_ES","og_type":"article","og_title":"Exposici\u00f3: Latencia, Engendrar un deseo &#8211; Poblenou Urban District","og_description":"Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, \"Latencia, Engendrar un deseo\", amb obres de l'artista Vilma Di Taranto.","og_url":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/","og_site_name":"Poblenou Urban District","article_modified_time":"2022-04-04T11:33:39+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2022\/03\/pud-agenda-6.jpg","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/","url":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/","name":"Exposici\u00f3: Latencia, Engendrar un deseo &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/#primaryimage"},"thumbnailUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2022\/03\/pud-agenda-6.jpg","datePublished":"2022-03-07T13:03:43+00:00","dateModified":"2022-04-04T11:33:39+00:00","description":"Nova exposici\u00f3 a la Galer\u00eda Chez Xefo, \"Latencia, Engendrar un deseo\", amb obres de l'artista Vilma Di Taranto.","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/"]]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/#primaryimage","url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2022\/03\/pud-agenda-6.jpg","contentUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2022\/03\/pud-agenda-6.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-latencia-engendrar-un-deseo\/2022-04-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/"},{"@type":"ListItem","position":3,"name":"Exposici\u00f3: Latencia, Engendrar un deseo"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website","url":"https:\/\/poblenouurbandistrict.com\/ca\/","name":"Poblenou Urban District","description":"Comunitat Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events\/10002650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events\/10002650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media\/26813"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media?parent=10002650"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tags?post=10002650"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=10002650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}