{"id":10003167,"date":"2022-04-21T17:51:39","date_gmt":"2022-04-21T15:51:39","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?post_type=tribe_events&#038;p=29145"},"modified":"2022-04-21T17:51:39","modified_gmt":"2022-04-21T15:51:39","slug":"exposicio-de-la-desfragmentacio-a-la-unificacio","status":"publish","type":"tribe_events","link":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/","title":{"rendered":"Exposici\u00f3: &#8220;De la Desfragmentaci\u00f3 a la Unificaci\u00f3&#8221;"},"content":{"rendered":"<p><\/p>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">El 22 d&#8217;abril en l&#8217;encantadora galeria de Chez Xefo en Poble Nou, Magda \u0106wik presentar\u00e0 al p\u00fablic una s\u00e8rie d&#8217;obres anomenades \u201cDe la Defragmentaci\u00f3n a la Unificaci\u00f3\u201d, una exposici\u00f3 que vol portar a l&#8217;espectador a una experi\u00e8ncia significativa en la qual l&#8217;artista compartir\u00e0 algunes de les seves \u201ceines cat\u00e0rtiques\u201d que li van ser revelades en les seves \u00faltimes meditacions i recerques cient\u00edfiques. Disponible fins al 8 de maig.<\/div>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El 22 d&#8217;abril en l&#8217;encantadora galeria de Chez Xefo en Poble Nou, Magda \u0106wik presentar\u00e0 al p\u00fablic una s\u00e8rie d&#8217;obres&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/\">M\u00e9s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":29149,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[3564,3553],"class_list":["post-10003167","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-art","tribe_events_cat-exposicion","cat_art","cat_exposicion","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3: &quot;De la Desfragmentaci\u00f3 a la Unificaci\u00f3&quot; &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3: &quot;De la Desfragmentaci\u00f3 a la Unificaci\u00f3&quot; &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"El 22 d&#8217;abril en l&#8217;encantadora galeria de Chez Xefo en Poble Nou, Magda \u0106wik presentar\u00e0 al p\u00fablic una s\u00e8rie d&#8217;obres... M\u00e9s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050507\/chez-xefo-square.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/\",\"name\":\"Exposici\u00f3: \\\"De la Desfragmentaci\u00f3 a la Unificaci\u00f3\\\" &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/04\\\/25050507\\\/chez-xefo-square.jpg\",\"datePublished\":\"2022-04-21T15:51:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/04\\\/25050507\\\/chez-xefo-square.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/04\\\/25050507\\\/chez-xefo-square.jpg\",\"width\":2480,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/exposicio-de-la-desfragmentacio-a-la-unificacio\\\/2022-04-28\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exposici\u00f3: &#8220;De la Desfragmentaci\u00f3 a la Unificaci\u00f3&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunitat Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3: \"De la Desfragmentaci\u00f3 a la Unificaci\u00f3\" &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/","og_locale":"ca_ES","og_type":"article","og_title":"Exposici\u00f3: \"De la Desfragmentaci\u00f3 a la Unificaci\u00f3\" &#8211; Poblenou Urban District","og_description":"El 22 d&#8217;abril en l&#8217;encantadora galeria de Chez Xefo en Poble Nou, Magda \u0106wik presentar\u00e0 al p\u00fablic una s\u00e8rie d&#8217;obres... M\u00e9s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/","og_site_name":"Poblenou Urban District","og_image":[{"width":2480,"height":2480,"url":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050507\/chez-xefo-square.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/","url":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/","name":"Exposici\u00f3: \"De la Desfragmentaci\u00f3 a la Unificaci\u00f3\" &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050507\/chez-xefo-square.jpg","datePublished":"2022-04-21T15:51:39+00:00","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/"]]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050507\/chez-xefo-square.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050507\/chez-xefo-square.jpg","width":2480,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/exposicio-de-la-desfragmentacio-a-la-unificacio\/2022-04-28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/poblenouurbandistrict.com\/ca\/agenda\/"},{"@type":"ListItem","position":3,"name":"Exposici\u00f3: &#8220;De la Desfragmentaci\u00f3 a la Unificaci\u00f3&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/ca\/#website","url":"https:\/\/poblenouurbandistrict.com\/ca\/","name":"Poblenou Urban District","description":"Comunitat Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events\/10003167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events\/10003167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media\/29149"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/media?parent=10003167"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tags?post=10003167"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=10003167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}