{"id":13496,"date":"2018-11-13T17:24:55","date_gmt":"2018-11-13T16:24:55","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.jpg"},"modified":"2023-05-10T12:56:38","modified_gmt":"2023-05-10T10:56:38","slug":"captura-de-pantalla-2018-11-13-a-las-17-24-32","status":"inherit","type":"attachment","link":"https:\/\/poblenouurbandistrict.com\/en\/programacio-poblenouopennight\/captura-de-pantalla-2018-11-13-a-las-17-24-32\/","title":{"rendered":"Captura de pantalla 2018-11-13 a las 17.24.32"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-13496","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Captura de pantalla 2018-11-13 a las 17.24.32 &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Captura de pantalla 2018-11-13 a las 17.24.32 &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-10T10:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png\" \/>\n\t<meta property=\"og:image:width\" content=\"695\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png\",\"name\":\"Captura de pantalla 2018-11-13 a las 17.24.32 &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\"},\"datePublished\":\"2018-11-13T16:24:55+00:00\",\"dateModified\":\"2023-05-10T10:56:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGRAMACI\u00d3N POBLENOU OPEN NIGHT 2018\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/programacio-poblenouopennight\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Captura de pantalla 2018-11-13 a las 17.24.32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Creative Community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Captura de pantalla 2018-11-13 a las 17.24.32 &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png","og_locale":"en_US","og_type":"article","og_title":"Captura de pantalla 2018-11-13 a las 17.24.32 &#8211; Poblenou Urban District","og_url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png","og_site_name":"Poblenou Urban District","article_modified_time":"2023-05-10T10:56:38+00:00","og_image":[{"width":695,"height":693,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png","url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png","name":"Captura de pantalla 2018-11-13 a las 17.24.32 &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/#website"},"datePublished":"2018-11-13T16:24:55+00:00","dateModified":"2023-05-10T10:56:38+00:00","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/en\/"},{"@type":"ListItem","position":2,"name":"PROGRAMACI\u00d3N POBLENOU OPEN NIGHT 2018","item":"https:\/\/poblenouurbandistrict.com\/en\/programacio-poblenouopennight\/"},{"@type":"ListItem","position":3,"name":"Captura de pantalla 2018-11-13 a las 17.24.32"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/en\/#website","url":"https:\/\/poblenouurbandistrict.com\/en\/","name":"Poblenou Urban District","description":"Creative Community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"618\" src=\"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-620x618.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":695,"height":693,"file":"2018\/11\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.jpg","filesize":92789,"sizes":{"medium":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-620x618.jpg","width":620,"height":618,"filesize":52119,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-620x618.jpg"},"large":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-640x638.jpg","width":640,"height":638,"filesize":54318,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-640x638.jpg"},"thumbnail":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-180x179.jpg","width":180,"height":179,"filesize":8955,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-180x179.jpg"},"third-content":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-470x469.jpg","width":470,"height":469,"filesize":35929,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-470x469.jpg"},"fourth-content":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-350x349.jpg","width":350,"height":349,"filesize":22690,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-350x349.jpg"},"puud-posts-excerpt":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-690x430.jpg","width":690,"height":430,"filesize":37421,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-690x430.jpg"},"puud-posts-yellow":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-690x430.jpg","width":690,"height":430,"filesize":37421,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-690x430.jpg"},"woocommerce_thumbnail":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-300x450.jpg","width":300,"height":450,"filesize":25134,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-300x450.jpg"},"woocommerce_single":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-600x598.jpg","width":600,"height":598,"filesize":49342,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-600x598.jpg"},"woocommerce_gallery_thumbnail":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32-100x100.jpg","width":100,"height":100,"filesize":3666,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32-100x100.jpg"},"full":{"file":"Captura-de-pantalla-2018-11-13-a-las-17.24.32.jpg","width":695,"height":693,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":13494,"source_url":"https:\/\/media.poblenouurbandistrict.com\/2018\/11\/25022432\/Captura-de-pantalla-2018-11-13-a-las-17.24.32.jpg","_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media\/13496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/comments?post=13496"}]}}