{"id":33934,"date":"2022-09-22T13:46:12","date_gmt":"2022-09-22T11:46:12","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2022\/09\/img-20220907-wa0003.jpg"},"modified":"2022-09-22T13:46:12","modified_gmt":"2022-09-22T11:46:12","slug":"img-20220907-wa0003","status":"inherit","type":"attachment","link":"https:\/\/poblenouurbandistrict.com\/en\/agenda\/exposicio-caixes-de-salvament-i-recital-homenatge-a-angel-guinda\/img-20220907-wa0003\/","title":{"rendered":"IMG-20220907-WA0003"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-33934","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG-20220907-WA0003 &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG-20220907-WA0003 &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:url\" content=\"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/09\\\/25054406\\\/img-20220907-wa0003.jpg\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/09\\\/25054406\\\/img-20220907-wa0003.jpg\",\"name\":\"IMG-20220907-WA0003 &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\"},\"datePublished\":\"2022-09-22T11:46:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/09\\\/25054406\\\/img-20220907-wa0003.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/09\\\/25054406\\\/img-20220907-wa0003.jpg\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/09\\\/25054406\\\/img-20220907-wa0003.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMG-20220907-WA0003\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Creative Community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG-20220907-WA0003 &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg","og_locale":"en_US","og_type":"article","og_title":"IMG-20220907-WA0003 &#8211; Poblenou Urban District","og_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg","og_site_name":"Poblenou Urban District","og_image":[{"width":1280,"height":1600,"url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg","url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg","name":"IMG-20220907-WA0003 &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/#website"},"datePublished":"2022-09-22T11:46:12+00:00","breadcrumb":{"@id":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/en\/"},{"@type":"ListItem","position":2,"name":"IMG-20220907-WA0003"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/en\/#website","url":"https:\/\/poblenouurbandistrict.com\/en\/","name":"Poblenou Urban District","description":"Creative Community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"775\" src=\"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-620x775.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":1600,"file":"2022\/09\/img-20220907-wa0003.jpg","filesize":168566,"sizes":{"woocommerce_thumbnail":{"file":"img-20220907-wa0003-300x450.jpg","width":300,"height":450,"filesize":18670,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-300x450.jpg"},"woocommerce_gallery_thumbnail":{"file":"img-20220907-wa0003-100x100.jpg","width":100,"height":100,"filesize":3071,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-100x100.jpg"},"woocommerce_single":{"file":"img-20220907-wa0003-600x750.jpg","width":600,"height":750,"filesize":40553,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-600x750.jpg"},"medium":{"file":"img-20220907-wa0003-620x775.jpg","width":620,"height":775,"filesize":49053,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-620x775.jpg"},"large":{"file":"img-20220907-wa0003-640x800.jpg","width":640,"height":800,"filesize":51528,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-640x800.jpg"},"thumbnail":{"file":"img-20220907-wa0003-180x225.jpg","width":180,"height":225,"filesize":8078,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-180x225.jpg"},"medium_large":{"file":"img-20220907-wa0003-768x960.jpg","width":768,"height":960,"filesize":63930,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-768x960.jpg"},"1536x1536":{"file":"img-20220907-wa0003-1229x1536.jpg","width":1229,"height":1536,"filesize":120912,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-1229x1536.jpg"},"half-width":{"file":"img-20220907-wa0003-1100x1375.jpg","width":1100,"height":1375,"filesize":105043,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-1100x1375.jpg"},"half-content":{"file":"img-20220907-wa0003-700x875.jpg","width":700,"height":875,"filesize":57402,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-700x875.jpg"},"third-content":{"file":"img-20220907-wa0003-470x588.jpg","width":470,"height":588,"filesize":32337,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-470x588.jpg"},"fourth-content":{"file":"img-20220907-wa0003-350x438.jpg","width":350,"height":438,"filesize":20498,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-350x438.jpg"},"puud-posts-excerpt":{"file":"img-20220907-wa0003-690x430.jpg","width":690,"height":430,"filesize":32078,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-690x430.jpg"},"puud-posts-yellow":{"file":"img-20220907-wa0003-690x430.jpg","width":690,"height":430,"filesize":32078,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003-690x430.jpg"},"full":{"file":"img-20220907-wa0003.jpg","width":1280,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33895,"source_url":"https:\/\/media.poblenouurbandistrict.com\/2022\/09\/25054406\/img-20220907-wa0003.jpg","_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media\/33934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/comments?post=33934"}]}}