{"id":12772,"date":"2018-05-17T14:30:04","date_gmt":"2018-05-17T12:30:04","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=12772"},"modified":"2018-05-17T14:34:27","modified_gmt":"2018-05-17T12:34:27","slug":"gracies-poblenou-open-day-2018","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/","title":{"rendered":"GRACIAS POR HACER POSIBLE EL POBLENOU OPEN DAY 2018"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12773\" src=\"https:\/\/media.poblenouurbandistrict.com\/2018\/05\/25021508\/open-day-2018-620x413.jpg\" alt=\"open day 2018\" width=\"620\" height=\"413\" \/><\/p>\n<p style=\"text-align: justify; padding-left: 570px;\">Xavier Mendiola\u00a0\u00a9<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a1El pasado s\u00e1bado celebramos la sexta edici\u00f3n del Poblenou Open Day!<\/strong> A pesar de que el tiempo no acompa\u00f1\u00f3, la ilusi\u00f3n y los buenos \u00e1nimos de todo el mundo hicieron de esta edici\u00f3n una jornada para no olvidar.<\/p>\n<p style=\"text-align: justify;\">De las novedades que presentaba esta edici\u00f3n, el Urban Hub aconteci\u00f3 uno de los lugares con m\u00e1s movimiento.\u00a0Los artistas de menci\u00f3n especial WAC, e Inocuo como artista invitado estuvieron interviniendo en directo, el p\u00fablico pudo disfrutar de una jornada con sesiones musicales y gastronom\u00eda <em>indoor<\/em> que eclipsaron el mal tiempo.<\/p>\n<p style=\"text-align: justify;\">Las obras que realizaron los artistas invitados <strong>Socatoba, Votto, Pablo Salvaje, Asis Percales, Alicia Vogel e Inocuo<\/strong>\u00a0en el Urban Hub <a href=\"https:\/\/poblenouurbandistrict.com\/es\/subhasta-de-peces-del-wac\/\">ser\u00e1n puestas a subasta<\/a> en breve, con el objetivo de reconocer el trabajo de los artistas y\u00a0recaudar fondos para los pr\u00f3ximos eventos y proyectos culturales de Poblenou Urban District.<\/p>\n<p style=\"text-align: justify;\">Queremos agradecer en primer lugar a todos los miembros de Poblenou Urban District que participaron en el Poblenou Open Day. Un total de 70 espacios abrieron sus puertas para mostrar el arte y la creatividad que hay en el barrio. Desde exposiciones de arte, actividades para los m\u00e1s peque\u00f1os, muestras de innovaci\u00f3n y tecnolog\u00eda, maridajes gastron\u00f3micos, m\u00fasica en directo&#8230; gracias a todos para hacer cada a\u00f1o que el Poblenou Open Day sea una jornada con propuestas atractivas y variadas que acercan el esp\u00edritu innovador y creativo del barrio al p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n agradecimientos a nuestros patrocinadores. <strong>San Miguel<\/strong> para acompa\u00f1arnos en todos los acontecimientos que organizamos y para hacer posible propuestas como los Workshops by San Miguel, dando la oportunidad a cuarenta personas de experimentar en primera persona actividades que se desarrollan en el barrio de Poblenou. A <strong>Montana Colors<\/strong> por apoyar iniciativas como el <strong>Windows Art Circuit<\/strong> que dan espacio y visibilidad a artistas emergentes. Gracias por proporcionar material para los artistas y hacer posible que las cristaleras del barrio se llenen de propuestas art\u00edsticas singulares. A\u00a0<strong>Valkiria\u00a0<\/strong>por ceder el espacio donde se hosped\u00f3 el Urban Hub y hacer posible que el Poblenou Open Day tuviese un hogar fant\u00e1stico para esta edici\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n a <strong>l\u2019Ajuntament de Barcelona<\/strong>, \u00a0<strong>Estudio Grande<\/strong>,<strong> Betev\u00e9, <\/strong><strong>La Plataforma,\u00a0<\/strong><strong>Servei Estaci\u00f3, Iaac Fab Lab, Bakery Group, La Cocina Palpita, Life in the Woods, \u00a0Naci\u00f3n Funk, C\u00f3digo Sound, Grisart Escola de Fotografia, \u00cfnta i Lamono Magazine.<\/strong><\/p>\n<p style=\"text-align: justify;\">Y por \u00faltimo, a vosotros, a todos los que nos acompa\u00f1aron en esta jornada y que, a\u00f1o tras a\u00f1o, nos apoyan en este proyecto. Desde Poblenou Urban District os queremos agradecer vuestra confianza a los que ya hace a\u00f1os que segu\u00eds al proyecto, y a los reci\u00e9n llegados que nos acab\u00e1is de descubrir esperamos que disfrut\u00e9is del camino que queda para recorrer tanto como nosotros.<\/p>\n<hr \/>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Xavier Mendiola\u00a0\u00a9 \u00a1El pasado s\u00e1bado celebramos la sexta edici\u00f3n del Poblenou Open Day! A pesar de que el tiempo no&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/\">More  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":12775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[15,657],"class_list":["post-12772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-open-day","tag-poblenou-open-day"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poblenou Urban District | Poblenou Open Day 2018, gr\u00e0cies!<\/title>\n<meta name=\"description\" content=\"Gr\u00e0cies a tothom per fer possible any rere any que el Poblenou Open Day sigui una data esperada per tots, i per fer-ho possible!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poblenou Urban District | Poblenou Open Day 2018, gr\u00e0cies!\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e0cies a tothom per fer possible any rere any que el Poblenou Open Day sigui una data esperada per tots, i per fer-ho possible!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-17T12:30:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-17T12:34:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/05\/open-day-2018-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/gracies-poblenou-open-day-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/gracies-poblenou-open-day-2018\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"GRACIAS POR HACER POSIBLE EL POBLENOU OPEN DAY 2018\",\"datePublished\":\"2018-05-17T12:30:04+00:00\",\"dateModified\":\"2018-05-17T12:34:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/gracies-poblenou-open-day-2018\\\/\"},\"wordCount\":1472,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/gracies-poblenou-open-day-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2018\\\/05\\\/25021511\\\/open-day-2018-1.jpg\",\"keywords\":[\"Open Day\",\"poblenou open day\"],\"articleSection\":[\"What's going on\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/\",\"name\":\"Poblenou Urban District | Poblenou Open Day 2018, gr\u00e0cies!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/gracies-poblenou-open-day-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2018\\\/05\\\/25021511\\\/open-day-2018-1.jpg\",\"datePublished\":\"2018-05-17T12:30:04+00:00\",\"dateModified\":\"2018-05-17T12:34:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"Gr\u00e0cies a tothom per fer possible any rere any que el Poblenou Open Day sigui una data esperada per tots, i per fer-ho possible!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2018\\\/05\\\/25021511\\\/open-day-2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2018\\\/05\\\/25021511\\\/open-day-2018-1.jpg\",\"width\":1152,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/gracies-poblenou-open-day-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GRACIAS POR HACER POSIBLE EL POBLENOU OPEN DAY 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Creative Community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poblenou Urban District | Poblenou Open Day 2018, gr\u00e0cies!","description":"Gr\u00e0cies a tothom per fer possible any rere any que el Poblenou Open Day sigui una data esperada per tots, i per fer-ho possible!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/","og_locale":"en_US","og_type":"article","og_title":"Poblenou Urban District | Poblenou Open Day 2018, gr\u00e0cies!","og_description":"Gr\u00e0cies a tothom per fer possible any rere any que el Poblenou Open Day sigui una data esperada per tots, i per fer-ho possible!","og_url":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/","og_site_name":"Poblenou Urban District","article_published_time":"2018-05-17T12:30:04+00:00","article_modified_time":"2018-05-17T12:34:27+00:00","og_image":[{"width":1152,"height":768,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2018\/05\/open-day-2018-1.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pnud","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/gracies-poblenou-open-day-2018\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/gracies-poblenou-open-day-2018\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"GRACIAS POR HACER POSIBLE EL POBLENOU OPEN DAY 2018","datePublished":"2018-05-17T12:30:04+00:00","dateModified":"2018-05-17T12:34:27+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/gracies-poblenou-open-day-2018\/"},"wordCount":1472,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/gracies-poblenou-open-day-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2018\/05\/25021511\/open-day-2018-1.jpg","keywords":["Open Day","poblenou open day"],"articleSection":["What's going on"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/","url":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/","name":"Poblenou Urban District | Poblenou Open Day 2018, gr\u00e0cies!","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/gracies-poblenou-open-day-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2018\/05\/25021511\/open-day-2018-1.jpg","datePublished":"2018-05-17T12:30:04+00:00","dateModified":"2018-05-17T12:34:27+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"Gr\u00e0cies a tothom per fer possible any rere any que el Poblenou Open Day sigui una data esperada per tots, i per fer-ho possible!","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2018\/05\/25021511\/open-day-2018-1.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2018\/05\/25021511\/open-day-2018-1.jpg","width":1152,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/en\/gracies-poblenou-open-day-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/en\/"},{"@type":"ListItem","position":2,"name":"GRACIAS POR HACER POSIBLE EL POBLENOU OPEN DAY 2018"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/en\/#website","url":"https:\/\/poblenouurbandistrict.com\/en\/","name":"Poblenou Urban District","description":"Creative Community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/12772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/comments?post=12772"}],"version-history":[{"count":5,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/12772\/revisions"}],"predecessor-version":[{"id":12783,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/12772\/revisions\/12783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media\/12775"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media?parent=12772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/categories?post=12772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/tags?post=12772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}