{"id":3666,"date":"2014-09-12T13:57:18","date_gmt":"2014-09-12T11:57:18","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=3666"},"modified":"2014-10-14T14:03:56","modified_gmt":"2014-10-14T12:03:56","slug":"les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/","title":{"rendered":"The voices of Poblenou: Interview with the mind behing Now Poblenou"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/3666\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Castellano\">Castellano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Castellano.<\/p>\n","protected":false},"author":5,"featured_media":3672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[52,737,600,740,426,739,738,736,16],"class_list":["post-3666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-can-felipa","tag-crowd-funding","tag-exhibicion","tag-fabrizio-bianchini","tag-inauguracion","tag-jupiterfab","tag-murales","tag-now-poblenou","tag-poblenou"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las voces del Poblenou: Entrevista con el creador de Now Poblenou<\/title>\n<meta name=\"description\" content=\"Tuvimos la oportunidad de sentarnos con Fabrizio Bianchini, conocido por su nombre art\u00edstico Jupiterfab, el creador del proyecto Now Poblenou.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las voces del Poblenou: Entrevista con el creador de Now Poblenou\" \/>\n<meta property=\"og:description\" content=\"Tuvimos la oportunidad de sentarnos con Fabrizio Bianchini, conocido por su nombre art\u00edstico Jupiterfab, el creador del proyecto Now Poblenou.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-12T11:57:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-14T12:03:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2014\/09\/web-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"504\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"The voices of Poblenou: Interview with the mind behing Now Poblenou\",\"datePublished\":\"2014-09-12T11:57:18+00:00\",\"dateModified\":\"2014-10-14T12:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/\"},\"wordCount\":2887,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2014\\\/09\\\/25003250\\\/web-3.jpg\",\"keywords\":[\"Can Felipa\",\"crowd funding\",\"exhibici\u00f3n\",\"fabrizio bianchini\",\"inauguraci\u00f3n\",\"jupiterfab\",\"murales\",\"now poblenou\",\"Poblenou\"],\"articleSection\":[\"What's going on\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/\",\"name\":\"Las voces del Poblenou: Entrevista con el creador de Now Poblenou\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2014\\\/09\\\/25003250\\\/web-3.jpg\",\"datePublished\":\"2014-09-12T11:57:18+00:00\",\"dateModified\":\"2014-10-14T12:03:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"Tuvimos la oportunidad de sentarnos con Fabrizio Bianchini, conocido por su nombre art\u00edstico Jupiterfab, el creador del proyecto Now Poblenou.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2014\\\/09\\\/25003250\\\/web-3.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2014\\\/09\\\/25003250\\\/web-3.jpg\",\"width\":504,\"height\":504,\"caption\":\"Jupiterfab (Fabrizio Bianchini)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las voces del Poblenou: Entrevista con el creador de Now Poblenou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Creative Community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las voces del Poblenou: Entrevista con el creador de Now Poblenou","description":"Tuvimos la oportunidad de sentarnos con Fabrizio Bianchini, conocido por su nombre art\u00edstico Jupiterfab, el creador del proyecto Now Poblenou.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/","og_locale":"en_US","og_type":"article","og_title":"Las voces del Poblenou: Entrevista con el creador de Now Poblenou","og_description":"Tuvimos la oportunidad de sentarnos con Fabrizio Bianchini, conocido por su nombre art\u00edstico Jupiterfab, el creador del proyecto Now Poblenou.","og_url":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/","og_site_name":"Poblenou Urban District","article_published_time":"2014-09-12T11:57:18+00:00","article_modified_time":"2014-10-14T12:03:56+00:00","og_image":[{"width":504,"height":504,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2014\/09\/web-3.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pnud","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"The voices of Poblenou: Interview with the mind behing Now Poblenou","datePublished":"2014-09-12T11:57:18+00:00","dateModified":"2014-10-14T12:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/"},"wordCount":2887,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2014\/09\/25003250\/web-3.jpg","keywords":["Can Felipa","crowd funding","exhibici\u00f3n","fabrizio bianchini","inauguraci\u00f3n","jupiterfab","murales","now poblenou","Poblenou"],"articleSection":["What's going on"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/","url":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/","name":"Las voces del Poblenou: Entrevista con el creador de Now Poblenou","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2014\/09\/25003250\/web-3.jpg","datePublished":"2014-09-12T11:57:18+00:00","dateModified":"2014-10-14T12:03:56+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"Tuvimos la oportunidad de sentarnos con Fabrizio Bianchini, conocido por su nombre art\u00edstico Jupiterfab, el creador del proyecto Now Poblenou.","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2014\/09\/25003250\/web-3.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2014\/09\/25003250\/web-3.jpg","width":504,"height":504,"caption":"Jupiterfab (Fabrizio Bianchini)"},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/en\/les-veus-del-poblenou-entrevista-amb-el-creador-de-now-poblenou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/en\/"},{"@type":"ListItem","position":2,"name":"Las voces del Poblenou: Entrevista con el creador de Now Poblenou"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/en\/#website","url":"https:\/\/poblenouurbandistrict.com\/en\/","name":"Poblenou Urban District","description":"Creative Community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/3666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/comments?post=3666"}],"version-history":[{"count":13,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/3666\/revisions"}],"predecessor-version":[{"id":3898,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/3666\/revisions\/3898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media\/3672"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media?parent=3666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/categories?post=3666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/tags?post=3666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}