{"id":43601,"date":"2024-01-04T12:56:44","date_gmt":"2024-01-04T11:56:44","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?p=43601"},"modified":"2024-01-04T12:57:10","modified_gmt":"2024-01-04T11:57:10","slug":"participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/","title":{"rendered":"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/poblenouurbandistrict.com\/ca\/wp-json\/wp\/v2\/posts\/43601\" class=\"qtranxs-available-language-link qtranxs-available-language-link-ca\" title=\"Catal\u00e0\">Catal\u00e0<\/a> and <a href=\"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/43601\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Castellano\">Castellano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Catal\u00e0 and Castellano.<\/p>\n","protected":false},"author":5,"featured_media":43616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3602],"tags":[],"class_list":["post-43601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poblenou"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Catal\u00e0 and Castellano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-04T11:56:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T11:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2024\/01\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1828\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou\",\"datePublished\":\"2024-01-04T11:56:44+00:00\",\"dateModified\":\"2024-01-04T11:57:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/\"},\"wordCount\":274,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/01\\\/25070748\\\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg\",\"articleSection\":[\"Poblenou\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/\",\"name\":\"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/01\\\/25070748\\\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg\",\"datePublished\":\"2024-01-04T11:56:44+00:00\",\"dateModified\":\"2024-01-04T11:57:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/01\\\/25070748\\\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/01\\\/25070748\\\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg\",\"width\":2560,\"height\":1828},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Creative Community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/","og_locale":"en_US","og_type":"article","og_title":"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou &#8211; Poblenou Urban District","og_description":"Sorry, this entry is only available in Catal\u00e0 and Castellano.","og_url":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/","og_site_name":"Poblenou Urban District","article_published_time":"2024-01-04T11:56:44+00:00","article_modified_time":"2024-01-04T11:57:10+00:00","og_image":[{"width":2560,"height":1828,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2024\/01\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pnud","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou","datePublished":"2024-01-04T11:56:44+00:00","dateModified":"2024-01-04T11:57:10+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/"},"wordCount":274,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/01\/25070748\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg","articleSection":["Poblenou"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/","url":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/","name":"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/01\/25070748\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg","datePublished":"2024-01-04T11:56:44+00:00","dateModified":"2024-01-04T11:57:10+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2024\/01\/25070748\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/01\/25070748\/vista-superior-manos-sosteniendo-juguete-ecologico-scaled.jpg","width":2560,"height":1828},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/en\/participa-en-la-campanya-solidaria-cap-nen-sense-joguina-al-casino-lalianca-del-poblenou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/en\/"},{"@type":"ListItem","position":2,"name":"Participa en la campanya solid\u00e0ria Cap Nen Sense Joguina al Casino L\u2019Alian\u00e7a del Poblenou"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/en\/#website","url":"https:\/\/poblenouurbandistrict.com\/en\/","name":"Poblenou Urban District","description":"Creative Community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/43601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/comments?post=43601"}],"version-history":[{"count":3,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/43601\/revisions"}],"predecessor-version":[{"id":43620,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/posts\/43601\/revisions\/43620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media\/43616"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/media?parent=43601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/categories?post=43601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/en\/wp-json\/wp\/v2\/tags?post=43601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}