{"id":48211,"date":"2024-11-21T14:29:10","date_gmt":"2024-11-21T13:29:10","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?p=48211"},"modified":"2024-11-21T18:28:19","modified_gmt":"2024-11-21T17:28:19","slug":"musica-i-teatre-amb-motiu-del-poblenou-open-night","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/","title":{"rendered":"Celebra el Poblenou Open Night con m\u00fasica y teatro"},"content":{"rendered":"<p>Poblenou es el Distrito Creativo y el centro neur\u00e1lgico de la comunidad creativa de Barcelona donde el talento esc\u00e9nico y musical se congrega para ofrecer una programaci\u00f3n de calidad. Teatros, salas de conciertos, espacios de creaci\u00f3n\u2026 Todos ellos se unen al Poblenou Open Night del 29 de noviembre para potenciar el futuro de las industrias creativas.<\/p>\n<h3><a href=\"https:\/\/www.bridge48.com\">Bridge 48<\/a><\/h3>\n<p>Ser\u00e1 el epicentro de la m\u00fasica y la creatividad femenina. A trav\u00e9s de sus cuatro espacios \u2013\u00a0<strong>B_48 LAB, B_48 LIVE, B_48 Gallery y B_48 Street View<\/strong>\u00a0\u2013 ofrecer\u00e1 una experiencia de m\u00fasica curada exclusivamente por mujeres artistas, mostrando el talento consagrado y\u00a0 emergente de las DJ\u2019s m\u00e1s innovadoras de la escena electr\u00f3nica y de nuestra comunidad.<\/p>\n<p>Los asistentes podr\u00e1n vivir la factor\u00eda musical que es Bridge 48 desde adentro, mientras disfrutan en una atm\u00f3sfera relajada de buena m\u00fasica, drinks \u00a1y mucho m\u00e1s!\u00a0Con m\u00e1s de 12 artistas en total, el evento ser\u00e1 una fiesta de sonidos frescos y din\u00e1micos, resaltando el talento de las mujeres en la m\u00fasica electr\u00f3nica.<\/p>\n<h4 style=\"text-align: center;\"><strong>18h &#8211; 00h<\/strong><\/h4>\n<h4 style=\"text-align: center;\"><strong>Llull, 48<\/strong><\/h4>\n<hr \/>\n<h3><a href=\"https:\/\/www.salabeckett.cat\">Sala Beckett<\/a><\/h3>\n<p>Disfruta de la obra\u00a0<b>\u2018<strong>Del fandom al troleig. Una s\u00e0tira del bla bla bla\u2019<\/strong><\/b>\u00a0de Berta Prieto. La historia de la voz rota de una generaci\u00f3n. Gracias al trabajo documental de Ximena White, conocemos la historia vital de Paula Mir\u00f3, ciberactivista que el 2024 empez\u00f3 su particular transici\u00f3n hacia una imparable estupiditzaci\u00f3personal. Para dejar de sufrir, cuanto m\u00e1s tonta mejor.<\/p>\n<p>No te pierdas las entradas a precio reducido para la obra,\u00a0para poder acceder a la promoci\u00f3n se tiene que hacer a trav\u00e9s de\u00a0<a href=\"https:\/\/salabeckett.koobin.cat\/?referer=YGdgYHBicHxzUXBqeXd7d3dlZn9hSWt3cmtxbmdJKCYl\">este enlace<\/a>.<\/p>\n<h4 style=\"text-align: center;\"><strong>19h &#8211; 23h<\/strong><\/h4>\n<h4 style=\"text-align: center;\"><strong>Pere IV, 228<\/strong><\/h4>\n<hr \/>\n<h3><a href=\"https:\/\/ovellanegramarina.com\/\">Ovella Negra<\/a><\/h3>\n<p>Ovella Negra, la taberna m\u00e1s famosa de Barcelona, es el lugar de encuentro predilecto de muchos j\u00f3venes para empezar la noche: un espacio dedicado a pasarlo bien y tomar buenas copas. Durante el Open Night ser\u00e1 la ocasi\u00f3n perfecta para descubrir nuevos talentos musicales, Microfusa trae a\u00a0<strong>Put0\u00a0Dani, Lara,\u00a0Andriu,\u00a0Sarazzz, Gaspar\u00a0No\u00e9s<\/strong>. La entrada es gratuita y encontrar\u00e1s su oferta habitual de bebida y comida.<\/p>\n<p style=\"text-align: center;\"><strong>18.45h \u2013 20:30h<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Zamora, 78<\/strong><\/p>\n<hr \/>\n<h3><a href=\"https:\/\/www.tnc.cat\/\">Teatre Nacional de Catalunya<\/a><\/h3>\n<p>Este Poblenou Open Night disfruta de Anna Kar\u00e8nina al Teatre Nacional de Catalunya.\u00a0En esta adaptaci\u00f3n esc\u00e9nica, Carme Portaceli rescata la Anna Kar\u00e8nina del esc\u00e1ndalo amoroso y la pose en escena para que sea enjuiciada, pero esta vez ella est\u00e1 decidida a explicarnos el que realmente sucedi\u00f3, el que realmente sinti\u00f3 y el que nadie, excepto quiz\u00e1s Tolst\u00f3i, tuvo en cuenta.<\/p>\n<p>Aprovecha el descuento antes del estreno de un 15% en tus entradas. Disponible hasta el 21\/11 a las 19h. Podr\u00e1s acceder a la\u00a0<a href=\"https:\/\/entrades.tnc.cat\/ca\/anna-karenina\">pesta\u00f1a de tarifas en el web del TNC<\/a>.<\/p>\n<p style=\"text-align: center;\"><strong>19h<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Pla\u00e7a de les Arts,1<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Poblenou es el Distrito Creativo y el centro neur\u00e1lgico de la comunidad creativa de Barcelona donde el talento esc\u00e9nico y&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":42543,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3560,3526,3348],"tags":[],"class_list":["post-48211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-teatre","category-open-night","category-musica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebra el Poblenou Open Night con m\u00fasica y teatro &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebra el Poblenou Open Night con m\u00fasica y teatro &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"Poblenou es el Distrito Creativo y el centro neur\u00e1lgico de la comunidad creativa de Barcelona donde el talento esc\u00e9nico y... M\u00e1s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-21T13:29:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T17:28:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2023\/11\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2397\" \/>\n\t<meta property=\"og:image:height\" content=\"1523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"Celebra el Poblenou Open Night con m\u00fasica y teatro\",\"datePublished\":\"2024-11-21T13:29:10+00:00\",\"dateModified\":\"2024-11-21T17:28:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/\"},\"wordCount\":974,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2023\\\/11\\\/25065942\\\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg\",\"articleSection\":[\"Teatro\",\"Open Night\",\"M\u00fasica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/\",\"name\":\"Celebra el Poblenou Open Night con m\u00fasica y teatro &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2023\\\/11\\\/25065942\\\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg\",\"datePublished\":\"2024-11-21T13:29:10+00:00\",\"dateModified\":\"2024-11-21T17:28:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2023\\\/11\\\/25065942\\\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2023\\\/11\\\/25065942\\\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg\",\"width\":2397,\"height\":1523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/musica-i-teatre-amb-motiu-del-poblenou-open-night\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebra el Poblenou Open Night amb m\u00fasica i teatre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebra el Poblenou Open Night con m\u00fasica y teatro &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/","og_locale":"es_ES","og_type":"article","og_title":"Celebra el Poblenou Open Night con m\u00fasica y teatro &#8211; Poblenou Urban District","og_description":"Poblenou es el Distrito Creativo y el centro neur\u00e1lgico de la comunidad creativa de Barcelona donde el talento esc\u00e9nico y... M\u00e1s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/","og_site_name":"Poblenou Urban District","article_published_time":"2024-11-21T13:29:10+00:00","article_modified_time":"2024-11-21T17:28:19+00:00","og_image":[{"width":2397,"height":1523,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2023\/11\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"Celebra el Poblenou Open Night con m\u00fasica y teatro","datePublished":"2024-11-21T13:29:10+00:00","dateModified":"2024-11-21T17:28:19+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/"},"wordCount":974,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2023\/11\/25065942\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg","articleSection":["Teatro","Open Night","M\u00fasica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/","url":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/","name":"Celebra el Poblenou Open Night con m\u00fasica y teatro &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2023\/11\/25065942\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg","datePublished":"2024-11-21T13:29:10+00:00","dateModified":"2024-11-21T17:28:19+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2023\/11\/25065942\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2023\/11\/25065942\/dsc-1819-bridge-48-studios-scaled-e1728574968852.jpg","width":2397,"height":1523},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/musica-i-teatre-amb-motiu-del-poblenou-open-night\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"Celebra el Poblenou Open Night amb m\u00fasica i teatre"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/48211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=48211"}],"version-history":[{"count":3,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/48211\/revisions"}],"predecessor-version":[{"id":48497,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/48211\/revisions\/48497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/42543"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=48211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=48211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=48211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}