{"id":51993,"date":"2025-09-02T14:09:53","date_gmt":"2025-09-02T12:09:53","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?p=51993"},"modified":"2025-09-03T13:21:17","modified_gmt":"2025-09-03T11:21:17","slug":"la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/","title":{"rendered":"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical"},"content":{"rendered":"<p><\/p>\n<p data-start=\"85\" data-end=\"266\"><strong>El Casino l\u2019Alian\u00e7a se prepara para celebrar la Fiesta Mayor, con una serie de actos destacados que combinar\u00e1n m\u00fasica en directo, danza y tradici\u00f3n entre el 7 y el 14 de septiembre.<\/strong><\/p>\n<p data-start=\"268\" data-end=\"836\">Las actividades comenzar\u00e1n el <strong>domingo 7 de septiembre a las 18:00 con el recital <em data-start=\"349\" data-end=\"366\">La Bella Napoli<\/em><\/strong>, un tributo a la canci\u00f3n napolitana protagonizado por el tenor Albert Pros-Deprius, acompa\u00f1ado por el Coro y la Orquesta de C\u00e1mara Harmonia y Laetitia Barbera a la mandolina. Este espect\u00e1culo ofrecer\u00e1 un recorrido por las melod\u00edas m\u00e1s emblem\u00e1ticas de N\u00e1poles, con piezas como \u201cParlami d\u2019amore, Mari\u00f9\u201d y \u201cSanta Lucia Luntana\u201d, que transportar\u00e1n al p\u00fablico a la belleza y emotividad del sur de Italia. Las entradas se pueden adquirir a trav\u00e9s de la plataforma Entr\u00e0polis.<\/p>\n<p data-start=\"838\" data-end=\"1171\">El <strong>lunes 8 de septiembre a partir de las 19:00 tendr\u00e1 lugar la Diada Sardanista en la Rotonda del Casino<\/strong>. La actividad incluye un taller de sardanas con la colaboraci\u00f3n de Som Sardana, seguido de un baile de sardanas con la Cobla Mediterr\u00e0nia. Esta propuesta es gratuita y pretende fomentar la tradici\u00f3n catalana del baile colectivo.<\/p>\n<p data-start=\"1173\" data-end=\"1368\">El <strong>jueves 11 de septiembre, a las 20:00, la Banda Municipal de Barcelona<\/strong> ofrecer\u00e1 un concierto gratuito que se podr\u00e1 seguir con entradas disponibles en taquilla y en la Coordinadora de Entidades.<\/p>\n<p data-start=\"1370\" data-end=\"1750\">El fin de semana siguiente, <strong>viernes 12 y s\u00e1bado 13 de septiembre a las 19:00<\/strong>, L\u2019Alian\u00e7a acoger\u00e1 la 11\u00aa edici\u00f3n del Barcelona Lindy Exchange, un festival dedicado al lindy hop que apuesta por la m\u00fasica en directo y el baile social, sin competiciones. Organizado por BCNSwing, este evento espera reunir aficionados y profesionales de todo el mundo en un ambiente festivo y acogedor.<\/p>\n<p data-start=\"1752\" data-end=\"2067\">Para cerrar la Fiesta Mayor, el domingo 14 de septiembre a las 18:30 se podr\u00e1 disfrutar de la Cantada de Habaneras con el grupo Port Bo, una formaci\u00f3n emblem\u00e1tica nacida en 1966 en Calella de Palafrugell y conocida por mantener viva la tradici\u00f3n de este g\u00e9nero musical. Las entradas est\u00e1n disponibles en Entr\u00e0polis.<\/p>\n<p data-start=\"2069\" data-end=\"2217\"><strong>Con esta programaci\u00f3n, la Fiesta Mayor del Poblenou en el Casino l\u2019Alian\u00e7a ofrece una experiencia cultural y festiva para todos los gustos y edades.<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El Casino l\u2019Alian\u00e7a se prepara para celebrar la Fiesta Mayor, con una serie de actos destacados que combinar\u00e1n m\u00fasica en&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":46191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3602],"tags":[],"class_list":["post-51993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poblenou"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"El Casino l\u2019Alian\u00e7a se prepara para celebrar la Fiesta Mayor, con una serie de actos destacados que combinar\u00e1n m\u00fasica en... M\u00e1s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-02T12:09:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T11:21:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2024\/06\/casino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1074\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical\",\"datePublished\":\"2025-09-02T12:09:53+00:00\",\"dateModified\":\"2025-09-03T11:21:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/\"},\"wordCount\":1119,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/06\\\/25073956\\\/casino.jpg\",\"articleSection\":[\"Poblenou\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/\",\"name\":\"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/06\\\/25073956\\\/casino.jpg\",\"datePublished\":\"2025-09-02T12:09:53+00:00\",\"dateModified\":\"2025-09-03T11:21:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/06\\\/25073956\\\/casino.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2024\\\/06\\\/25073956\\\/casino.jpg\",\"width\":1074,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Festa Major del Poblenou arriba al Casino L\u2019Alian\u00e7a amb una variada programaci\u00f3 cultural i musical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/","og_locale":"es_ES","og_type":"article","og_title":"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical &#8211; Poblenou Urban District","og_description":"El Casino l\u2019Alian\u00e7a se prepara para celebrar la Fiesta Mayor, con una serie de actos destacados que combinar\u00e1n m\u00fasica en... M\u00e1s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/","og_site_name":"Poblenou Urban District","article_published_time":"2025-09-02T12:09:53+00:00","article_modified_time":"2025-09-03T11:21:17+00:00","og_image":[{"width":1074,"height":715,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2024\/06\/casino.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical","datePublished":"2025-09-02T12:09:53+00:00","dateModified":"2025-09-03T11:21:17+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/"},"wordCount":1119,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/06\/25073956\/casino.jpg","articleSection":["Poblenou"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/","url":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/","name":"La Festa Major de Poblenou llega al Casino L\u2019Alian\u00e7a con una variada programaci\u00f3n cultural y musical &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/06\/25073956\/casino.jpg","datePublished":"2025-09-02T12:09:53+00:00","dateModified":"2025-09-03T11:21:17+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2024\/06\/25073956\/casino.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2024\/06\/25073956\/casino.jpg","width":1074,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/la-festa-major-del-poblenou-arriba-al-casino-lalianca-amb-una-variada-programacio-cultural-i-musical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Festa Major del Poblenou arriba al Casino L\u2019Alian\u00e7a amb una variada programaci\u00f3 cultural i musical"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/51993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=51993"}],"version-history":[{"count":3,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/51993\/revisions"}],"predecessor-version":[{"id":51996,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/51993\/revisions\/51996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/46191"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=51993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=51993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=51993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}