{"id":56761,"date":"2026-06-25T12:51:56","date_gmt":"2026-06-25T10:51:56","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?p=56761"},"modified":"2026-06-25T12:51:56","modified_gmt":"2026-06-25T10:51:56","slug":"lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/","title":{"rendered":"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n."},"content":{"rendered":"<p><\/p>\n<div id=\"model-response-message-contentr_e7e5c7feebe63212\" class=\"markdown markdown-main-panel enable-luminous-fast-follows stronger enable-updated-hr-color\" dir=\"ltr\" aria-live=\"polite\" aria-busy=\"false\">\n<p data-path-to-node=\"2\">LaCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, cierra su tercer a\u00f1o de trayectoria consolid\u00e1ndose como la plataforma de referencia para acercar las artes en vivo a los centros educativos de Catalunya.<\/p>\n<p data-path-to-node=\"2\">El programa, impulsado por <a href=\"https:\/\/www.auditori.cat\/ca\/\">L&#8217;Auditori<\/a>, el Gran Teatre del Liceu, el Mercat de les Flors, el Palau de la M\u00fasica Catalana, el Teatre Lliure y el <a href=\"https:\/\/www.tnc.cat\/es\">Teatre Nacional de Catalunya<\/a>, cierra el curso 2025-26 con casi 175.000 participantes de m\u00e1s de 1.600 centros catalanes y alcanza las 4.300 reservas en su plataforma.<\/p>\n<p data-path-to-node=\"2\">Como novedad para el pr\u00f3ximo curso, laCultivadora ampliar\u00e1 las formaciones a docentes en diferentes puntos del territorio catal\u00e1n y pondr\u00e1 en marcha una prueba piloto para ofrecer estancias culturales en Barcelona a centros educativos de las zonas m\u00e1s alejadas de la capital catalana.<\/p>\n<p data-path-to-node=\"2\">Entre estas formaciones, el curso pasado se estren\u00f3 la formaci\u00f3n de larga duraci\u00f3n para docentes, bajo el nombre de P\u00fablics creatius: una propuesta en la que los docentes han podido disfrutar de seis espect\u00e1culos de la programaci\u00f3n general de los seis equipamientos, y de una formaci\u00f3n de 50 h dedicada a las arts en vivo que finalizar\u00e1 el pr\u00f3ximo 26 de junio, en el Palau de la M\u00fasica Catalana (Petit Palau), con la creaci\u00f3n de un espect\u00e1culo participativo protagonizado por ellos mismos, L&#8217;Hidroavi\u00f3. P\u00fablics creatius se repetir\u00e1 la pr\u00f3xima temporada y correr\u00e1 a cargo de Jordi Oriol y Carles Pedragosa.<\/p>\n<h4 data-path-to-node=\"3\">laCultivadora, m\u00e1s actividades y un curso 2026-2027 con mirada de pa\u00eds<\/h4>\n<p data-path-to-node=\"3\">Este jueves 25 de junio se ha iniciado en la <a href=\"https:\/\/public-eur.mkt.dynamics.com\/api\/orgs\/c743baeb-4fbf-ee11-9075-000d3a3a024b\/r\/9MsOKoOdAkiCpqBNdaQBAAAAAAA?msdynmkt_target=%7B%22TargetUrl%22%3A%22http%253A%252F%252Fwww.lacultivadora.cat%252F%22%2C%22RedirectOptions%22%3A%7B%225%22%3Anull%2C%221%22%3Anull%7D%7D&amp;msdynmkt_digest=RNtbeVdHOxEvVkrBBR06cIcH2F5qWSSOOr9p%2Bz7LoaA%3D&amp;msdynmkt_secretVersion=7bb221762d0c46939816d3a5592b1359\">web de laCultivadora<\/a> el proceso de inscripci\u00f3n de los centros al nuevo curso que contar\u00e1 con una oferta de 149 actividades y 408 recursos digitales gratuitos para docentes, artistas y alumnos.<\/p>\n<p data-path-to-node=\"3\">M\u00e1s all\u00e1 de la oferta de actividades, y desde el convencimiento de que el acceso a la cultura no puede depender del lugar donde se encuentre cada centro educativo, para el curso 2026-2027, laCultivadora da un nuevo paso para hacer posible que alumnos y docentes de todo el pa\u00eds puedan participar de sus propuestas.<\/p>\n<p data-path-to-node=\"3\">Por otra parte, laCultivadora continuar\u00e1 ampliando sus formaciones para docentes en el territorio. Despu\u00e9s de que el curso pasado estas sesiones llegaran a Tremp, Lleida, Tarragona, Calafell, Girona, Berga y Tortosa, la temporada 2026-27 se extender\u00e1n a la totalidad de los 11 servicios territoriales de Educaci\u00f3n de Catalunya incorporando nuevos \u00e1mbitos como el Vall\u00e8s Oriental, el Vall\u00e8s Occidental, el Maresme y el Baix Llobregat, ofreciendo m\u00e1s de 15 formaciones.<\/p>\n<h4 data-path-to-node=\"4\">La oferta del <a href=\"https:\/\/www.tnc.cat\/es\">Teatre Nacional de Catalunya<\/a><\/h4>\n<p data-path-to-node=\"4\">A trav\u00e9s de laCultivadora, el Teatre Nacional de Catalunya ofrece 47 funciones en horario escolar de 13 espect\u00e1culos, con t\u00edtulos como Gota y Tenet para primaria, y L\u2019Hostal de les tres Cam\u00e8lies y R\u00e0bia para secundaria. Para enriquecer la experiencia de recepci\u00f3n de estos espect\u00e1culos, el TNC ofrece gu\u00edas did\u00e1cticas, actividades postfunci\u00f3n, Un dia al TNC y tambi\u00e9n itinerarios con la complicidad de los otros equipamientos de laCultivadora.<\/p>\n<p data-path-to-node=\"4\">Durante la temporada, el TNC facilita diferentes talleres para trabajar elementos esc\u00e9nicos como la luz, la voz, el sonido y el vestuario, as\u00ed como visitas guiadas que permiten descubrir la variedad de oficios y vocaciones que confluyen en un teatro como el TNC.<\/p>\n<p data-path-to-node=\"4\">Adem\u00e1s, impulsa proyectos de largo recorrido como Teatre i Acci\u00f3, para disfrutar de una experiencia de creaci\u00f3n. En cuanto a los docentes, mantiene tres jornadas formativas y el curso de verano, espacios para disfrutar del teatro mientras adquieren recursos aplicables en el aula.<\/p>\n<h4 data-path-to-node=\"4\">La oferta de <a href=\"https:\/\/www.auditori.cat\/ca\/\">L\u2019Auditori<\/a><\/h4>\n<p data-path-to-node=\"4\">L\u2019Auditori ofrece a trav\u00e9s de laCultivadora un total de<strong> 20 actividades, 170 sesiones,<\/strong> entre las cuales hay<strong> 12 conciertos<\/strong>: el estreno de Xopluc, la renovaci\u00f3n de Out of the [Cage] vol.2, itinerario Out of the [Cage] vol.2, el 10\u00ba aniversario de Pica-so, Els colors del metall, Toy Box, itinerario Toy Box, Monstres, Band\u00e0stic, H\u00e4ndel&amp;Friends, Mamemi&#8230; Mozart!, Tutti fan piu, itinerario La r\u00e0bia en colaboraci\u00f3n con el TNC, itinerario G\u00e8nesi en colaboraci\u00f3n con el Teatre Lliure. Adem\u00e1s, L\u2019Auditori ofrece 3 proyectos participativos para el alumnado de primaria y de secundaria: Cant\u00e0nia Gaudir Gaud\u00ed, Els compositors entren a l\u2019aula y Hip-hop a secund\u00e0ria. Tambi\u00e9n ofrecemos una sesi\u00f3n de formaci\u00f3n para educadoras de escuela cuna y maestros de educaci\u00f3n infantil del concierto dirigido a los m\u00e1s peque\u00f1os: la sesi\u00f3n de formaci\u00f3n de Xopluc donde se facilitar\u00e1n las herramientas y recursos para poder trabajar los conciertos en el aula. Por \u00faltimo, desde L\u2019Auditori se promueve la formaci\u00f3n P\u00fablics creatius, una propuesta de formaci\u00f3n dirigida a docentes que contiene una vertiente de escuela de espectadores y otra de laboratorio de creaci\u00f3n y que L\u2019Auditori acoger\u00e1 la muestra en el mes de junio.<\/p>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>LaCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, cierra su tercer a\u00f1o de&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":56770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3560,3348],"tags":[],"class_list":["post-56761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-teatre","category-musica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n. &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n. &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"LaCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, cierra su tercer a\u00f1o de... M\u00e1s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T10:51:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2026\/06\/23103935\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n.\",\"datePublished\":\"2026-06-25T10:51:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/\"},\"wordCount\":2431,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2026\\\/06\\\/23103935\\\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg\",\"articleSection\":[\"Teatro\",\"M\u00fasica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/\",\"name\":\"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n. &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2026\\\/06\\\/23103935\\\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg\",\"datePublished\":\"2026-06-25T10:51:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2026\\\/06\\\/23103935\\\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2026\\\/06\\\/23103935\\\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg\",\"width\":2560,\"height\":1463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"laCultivadora, el projecte educatiu impulsat pels sis equipaments esc\u00e8nics i musicals nacionals de Catalunya, amplia la seva pres\u00e8ncia arreu del territori catal\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n. &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/","og_locale":"es_ES","og_type":"article","og_title":"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n. &#8211; Poblenou Urban District","og_description":"LaCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, cierra su tercer a\u00f1o de... M\u00e1s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/","og_site_name":"Poblenou Urban District","article_published_time":"2026-06-25T10:51:56+00:00","og_image":[{"width":2560,"height":1463,"url":"https:\/\/media.poblenouurbandistrict.com\/2026\/06\/23103935\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n.","datePublished":"2026-06-25T10:51:56+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/"},"wordCount":2431,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2026\/06\/23103935\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg","articleSection":["Teatro","M\u00fasica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/","url":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/","name":"laCultivadora, el proyecto educativo impulsado por los seis equipamientos esc\u00e9nicos y musicales nacionales de Catalunya, ampl\u00eda su presencia en todo el territorio catal\u00e1n. &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2026\/06\/23103935\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg","datePublished":"2026-06-25T10:51:56+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2026\/06\/23103935\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2026\/06\/23103935\/cantania-lultim-rellotge-de-4t-a-6e-de-primaria-foto-may-zircus-e1782204002616.jpg","width":2560,"height":1463},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/lacultivadora-el-projecte-educatiu-impulsat-pels-sis-equipaments-escenics-i-musicals-nacionals-de-catalunya-amplia-la-seva-presencia-arreu-del-territori-catala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"laCultivadora, el projecte educatiu impulsat pels sis equipaments esc\u00e8nics i musicals nacionals de Catalunya, amplia la seva pres\u00e8ncia arreu del territori catal\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/56761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=56761"}],"version-history":[{"count":12,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/56761\/revisions"}],"predecessor-version":[{"id":56775,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/56761\/revisions\/56775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/56770"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=56761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=56761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=56761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}