{"id":6519,"date":"2015-07-07T12:47:52","date_gmt":"2015-07-07T10:47:52","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=6519"},"modified":"2015-07-07T12:47:52","modified_gmt":"2015-07-07T10:47:52","slug":"taller-per-startups-en-busca-de-financament","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/","title":{"rendered":"Taller para startups en busca de financiaci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala-640x426.jpg\" alt=\"Sala Valkiria Hub Space\" width=\"640\" height=\"426\" class=\"aligncenter size-large wp-image-6520\" \/><\/p>\n<p><\/p>\n<h1>Todos los detalles y ventajas del programa europeo Horizon 2020 explicadas en Valkiria Hub Space<\/h1>\n<p>Despu\u00e9s de disfrutar la semana pasada del evento en Barcelona de la Semana de la Innovaci\u00f3n Europea (Youth Innovation Week), <b>Valkiria Hub Space<\/b> organiza este jueves 9 de julio un taller para asesorar en el acceso al programa <b>Horizon 2020<\/b>.<\/p>\n<p><b>Horizon 2020<\/b> es el plan de la Uni\u00f3n Europea para financiar, a fondo perdido, diferentes proyectos innovadores. La financiaci\u00f3n es uno de los temas m\u00e1s importantes para cualquier startup. Estas ayudas van desde \u20ac 50.000 a \u20ac 2.500.000. En el taller de EYIF y <b>Valkiria Hub Space<\/b> se explicar\u00e1n todos los tr\u00e1mites a seguir &#8211; paso a paso &#8211; de manera pr\u00e1ctica y por parte de expertos.<\/p>\n<p>La ponencia estar\u00e1 liderada por Kurmadev Chatterjee, Fundador y Presidente de EYIF. Ha sido evaluador para la Comisi\u00f3n Europea y en los \u00faltimos a\u00f1os ha trabajado en el dise\u00f1o y configuraci\u00f3n del SME Instrument, que es el proceso para acceder a <b>Horizon 2020<\/b>.<\/p>\n<p>Si quieres conocer todo el proceso de las manos de un experto, inscr\u00edbete ya en el <a href=\"http:\/\/www.eventbrite.com\/e\/eu-funding-for-startups-full-day-workshop-on-sme-instrument-tickets-16823232742?aff=es2\">siguiente enlace<\/a>.<\/p>\n<p>Sobre\u00a0<b>Valkiria Hub Space<\/b>:\u00a0Una plataforma empresarial enfocada a prestar un asesoramiento de negocio integral, que combinan con la organizaci\u00f3n de eventos corporativos con valor a\u00f1adido. Dentro de la plataforma, tambi\u00e9n promueven formaci\u00f3n y programas de\u00a0mentoring\u00a0para emprendedores y\u00a0startups.<\/p>\n<hr\/>\n<h3>TALLER SOBRE HORIZON 2020\u2028<br \/>\nVALKIRIA HUB SPACE (C\/ PUJADES 126)\u2028<br \/>\nJUEVES 9 DE JULIO, DE 10.00H A 17.00H<\/h3>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Todos los detalles y ventajas del programa europeo Horizon 2020 explicadas en Valkiria Hub Space Despu\u00e9s de disfrutar la semana&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":6520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1542,1293,473,479,271,744],"class_list":["post-6519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-horizon2020","tag-startups","tag-talleres","tag-tallers","tag-valkiria-hub-space","tag-workshops"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taller per startups en busca de finan\u00e7ament<\/title>\n<meta name=\"description\" content=\"Despr\u00e9s de gaudir del Youth Innovation Week, Valkiria Hub Space organitza aquest 9 de juliol un taller per assessorar en l\u2019acc\u00e8s al programa Horizon 2020\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taller per startups en busca de finan\u00e7ament\" \/>\n<meta property=\"og:description\" content=\"Despr\u00e9s de gaudir del Youth Innovation Week, Valkiria Hub Space organitza aquest 9 de juliol un taller per assessorar en l\u2019acc\u00e8s al programa Horizon 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-07T10:47:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"977\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"Taller para startups en busca de financiaci\u00f3n\",\"datePublished\":\"2015-07-07T10:47:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/\"},\"wordCount\":510,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/07\\\/25010726\\\/sala.jpg\",\"keywords\":[\"horizon2020\",\"startups\",\"Talleres\",\"Tallers\",\"Valkiria Hub Space\",\"workshops\"],\"articleSection\":[\"Est\u00e1 pasando\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/\",\"name\":\"Taller per startups en busca de finan\u00e7ament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/07\\\/25010726\\\/sala.jpg\",\"datePublished\":\"2015-07-07T10:47:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"Despr\u00e9s de gaudir del Youth Innovation Week, Valkiria Hub Space organitza aquest 9 de juliol un taller per assessorar en l\u2019acc\u00e8s al programa Horizon 2020\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/07\\\/25010726\\\/sala.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/07\\\/25010726\\\/sala.jpg\",\"width\":977,\"height\":651,\"caption\":\"Sala Valkiria Hub Space\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/taller-per-startups-en-busca-de-financament\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taller para startups en busca de financiaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taller per startups en busca de finan\u00e7ament","description":"Despr\u00e9s de gaudir del Youth Innovation Week, Valkiria Hub Space organitza aquest 9 de juliol un taller per assessorar en l\u2019acc\u00e8s al programa Horizon 2020","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/","og_locale":"es_ES","og_type":"article","og_title":"Taller per startups en busca de finan\u00e7ament","og_description":"Despr\u00e9s de gaudir del Youth Innovation Week, Valkiria Hub Space organitza aquest 9 de juliol un taller per assessorar en l\u2019acc\u00e8s al programa Horizon 2020","og_url":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-07-07T10:47:52+00:00","og_image":[{"width":977,"height":651,"url":"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"Taller para startups en busca de financiaci\u00f3n","datePublished":"2015-07-07T10:47:52+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/"},"wordCount":510,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala.jpg","keywords":["horizon2020","startups","Talleres","Tallers","Valkiria Hub Space","workshops"],"articleSection":["Est\u00e1 pasando"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/","url":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/","name":"Taller per startups en busca de finan\u00e7ament","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala.jpg","datePublished":"2015-07-07T10:47:52+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"Despr\u00e9s de gaudir del Youth Innovation Week, Valkiria Hub Space organitza aquest 9 de juliol un taller per assessorar en l\u2019acc\u00e8s al programa Horizon 2020","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/07\/25010726\/sala.jpg","width":977,"height":651,"caption":"Sala Valkiria Hub Space"},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/taller-per-startups-en-busca-de-financament\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"Taller para startups en busca de financiaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=6519"}],"version-history":[{"count":1,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6519\/revisions"}],"predecessor-version":[{"id":6521,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6519\/revisions\/6521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/6520"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=6519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=6519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=6519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}