{"id":6673,"date":"2015-09-07T12:49:47","date_gmt":"2015-09-07T10:49:47","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=6673"},"modified":"2015-09-08T11:04:44","modified_gmt":"2015-09-08T09:04:44","slug":"bau-design-forum-jornades-interdisciplinars-de-disseny","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/","title":{"rendered":"Bau Design Forum, jornadas interdisciplinares de dise\u00f1o"},"content":{"rendered":"<p><figure id=\"attachment_6674\" aria-describedby=\"caption-attachment-6674\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25010847\/varvara_mar_wishingwall-640x436.jpg\" alt=\"Varvara &amp; Mar &quot;Wishing Wall&quot;\" width=\"640\" height=\"436\" class=\"size-large wp-image-6674\" \/><figcaption id=\"caption-attachment-6674\" class=\"wp-caption-text\">Varvara &#038; Mar \u00abWishing Wall\u00bb<\/figcaption><\/figure><\/p>\n<p><\/p>\n<h1>Bau organiza Bau Design Forum, unas jornadas interdisciplinares de dise\u00f1o<\/h1>\n<p>Del 14 al 16 de septiembre, <b>Bau<\/b> organiza <b>Bau Design Forum<\/b>, unas jornadas interdisciplinares de dise\u00f1o con conferencias y workshops que contar\u00e1n con figuras como: Rocco Verdult, Jean Pierre Blanc, Toormix, Luca Macri o Gabor Bene. <b>Bau Design Forum<\/b> nace con la voluntad de ser un punto de encuentro y reflexi\u00f3n en torno a la multidisciplinariedad del dise\u00f1o, su funci\u00f3n en la sociedad y su capacidad de transformaci\u00f3n social. <\/p>\n<p>M\u00e1s informaci\u00f3n en la <a href=\"http:\/\/www.baudesignforum.com\/\">web<\/a> de <b>Bau Design Forum<\/b>. Inscripci\u00f3n on-line a trav\u00e9s de <a href=\"https:\/\/www.ticketea.com\/entradas-taller-bau-design-forum-typomatrix-arcangela-regis\/\">Ticketea<\/a>.<\/p>\n<p><b>M\u00e1s sobre\u00a0<a href=\"http:\/\/www.baued.es\/\">Bau<\/a>:<\/b>\u00a0un centro que imparte estudios universitarios en el \u00e1mbito del dise\u00f1o. Emplazado en el distrito 22@ de Barcelona, ciudad conocida en todo el mundo por el dise\u00f1o,\u00a0Bau\u00a0se ubica en un recinto industrial de m\u00e1s de 6.000 m2 habilitado con espacios espec\u00edficos para la docencia y espacios polivalentes pensados para fomentar la creaci\u00f3n y la investigaci\u00f3n.<\/p>\n<hr\/>\n<h3>Bau Design Forum<br \/>\nBau, centro universitario de dise\u00f1o<br \/>\nCalle de Pujades, 99<br \/>\nDel 14 al 16 de septiembre 2015<\/h3>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Bau organiza Bau Design Forum, unas jornadas interdisciplinares de dise\u00f1o Del 14 al 16 de septiembre, Bau organiza Bau Design&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":6674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[9,1469,625,1602,178,122,1264],"class_list":["post-6673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-bau","tag-bau-centre-universitari-de-disseny","tag-charlas","tag-conferences","tag-conferencias","tag-disseny","tag-xerrades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bau Design Forum, jornades interdisciplinars de disseny<\/title>\n<meta name=\"description\" content=\"Bau, Centre Universitari de Disseny organitza Bau Design Forum, unes jornades interdisciplinars de disseny amb confer\u00e8ncies i workshops\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bau Design Forum, jornades interdisciplinars de disseny\" \/>\n<meta property=\"og:description\" content=\"Bau, Centre Universitari de Disseny organitza Bau Design Forum, unes jornades interdisciplinars de disseny amb confer\u00e8ncies i workshops\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-07T10:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-08T09:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/09\/varvara_mar_wishingwall.png\" \/>\n\t<meta property=\"og:image:width\" content=\"785\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"Bau Design Forum, jornadas interdisciplinares de dise\u00f1o\",\"datePublished\":\"2015-09-07T10:49:47+00:00\",\"dateModified\":\"2015-09-08T09:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/\"},\"wordCount\":404,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25010847\\\/varvara_mar_wishingwall.jpg\",\"keywords\":[\"BAU\",\"bau centre universitari de disseny\",\"charlas\",\"conferences\",\"Conferencias\",\"Disseny\",\"xerrades\"],\"articleSection\":[\"Est\u00e1 pasando\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/\",\"name\":\"Bau Design Forum, jornades interdisciplinars de disseny\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25010847\\\/varvara_mar_wishingwall.jpg\",\"datePublished\":\"2015-09-07T10:49:47+00:00\",\"dateModified\":\"2015-09-08T09:04:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"Bau, Centre Universitari de Disseny organitza Bau Design Forum, unes jornades interdisciplinars de disseny amb confer\u00e8ncies i workshops\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25010847\\\/varvara_mar_wishingwall.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25010847\\\/varvara_mar_wishingwall.jpg\",\"width\":785,\"height\":535,\"caption\":\"Varvara & Mar \\\"Wishing Wall\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/bau-design-forum-jornades-interdisciplinars-de-disseny\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bau Design Forum, jornadas interdisciplinares de dise\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bau Design Forum, jornades interdisciplinars de disseny","description":"Bau, Centre Universitari de Disseny organitza Bau Design Forum, unes jornades interdisciplinars de disseny amb confer\u00e8ncies i workshops","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/","og_locale":"es_ES","og_type":"article","og_title":"Bau Design Forum, jornades interdisciplinars de disseny","og_description":"Bau, Centre Universitari de Disseny organitza Bau Design Forum, unes jornades interdisciplinars de disseny amb confer\u00e8ncies i workshops","og_url":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-09-07T10:49:47+00:00","article_modified_time":"2015-09-08T09:04:44+00:00","og_image":[{"width":785,"height":535,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/09\/varvara_mar_wishingwall.png","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/bau-design-forum-jornades-interdisciplinars-de-disseny\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"Bau Design Forum, jornadas interdisciplinares de dise\u00f1o","datePublished":"2015-09-07T10:49:47+00:00","dateModified":"2015-09-08T09:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/bau-design-forum-jornades-interdisciplinars-de-disseny\/"},"wordCount":404,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25010847\/varvara_mar_wishingwall.jpg","keywords":["BAU","bau centre universitari de disseny","charlas","conferences","Conferencias","Disseny","xerrades"],"articleSection":["Est\u00e1 pasando"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/","url":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/","name":"Bau Design Forum, jornades interdisciplinars de disseny","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25010847\/varvara_mar_wishingwall.jpg","datePublished":"2015-09-07T10:49:47+00:00","dateModified":"2015-09-08T09:04:44+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"Bau, Centre Universitari de Disseny organitza Bau Design Forum, unes jornades interdisciplinars de disseny amb confer\u00e8ncies i workshops","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25010847\/varvara_mar_wishingwall.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25010847\/varvara_mar_wishingwall.jpg","width":785,"height":535,"caption":"Varvara & Mar \"Wishing Wall\""},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/bau-design-forum-jornades-interdisciplinars-de-disseny\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"Bau Design Forum, jornadas interdisciplinares de dise\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=6673"}],"version-history":[{"count":1,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6673\/revisions"}],"predecessor-version":[{"id":6675,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6673\/revisions\/6675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/6674"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=6673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=6673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=6673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}