{"id":6769,"date":"2015-09-28T13:02:51","date_gmt":"2015-09-28T11:02:51","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=6769"},"modified":"2015-09-28T13:02:51","modified_gmt":"2015-09-28T11:02:51","slug":"palo-alto-market-torna-un-altre-cop","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/","title":{"rendered":"Palo Alto Market, regreza una vez m\u00e1s"},"content":{"rendered":"<p><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/09\/12047000_970377273020098_6132034629719827883_n-640x234.png\" alt=\"Palo Alto Market, 2 y 4 de octubre\" width=\"640\" height=\"234\" class=\"aligncenter size-large wp-image-6771\" \/><\/p>\n<p><\/p>\n<h1>El primer fin de semana de los meses Octubre, Noviembre y Diciembre, Palo Alto Market vuelve de nuevo a Barcelona!<\/h1>\n<p>El 3 y 4 de Octubre se podr\u00e1 disfrutar en <b>Poblenou<\/b> de este mercado callejero: sofisticado y basado en el concepto de <i>street market<\/i> popular, este nuevo mercado se caracteriza por todo el mundo por el formato adaptado a una ciudad en diferentes tendencias art\u00edsticas que potencian la figura urbana. Un mercado donde, la creatividad es el n\u00facleo principal, combinando el talento y sensibilidad. Una selecci\u00f3n de ideas innovadoras dentro del mundo de la gastronom\u00eda, m\u00fasica, arte, dise\u00f1o y workshops ser\u00e1n los protagonistas de esta feria. La instalaci\u00f3n ocupa los cuatro calles exteriores del recinto y tres naves interiores donde, se ubicar\u00e1n un m\u00e1ximo de 150 expositores.<\/p>\n<p><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/09\/DSC_0215-640x361.jpg\" alt=\"Mediogesign\" width=\"640\" height=\"361\" class=\"aligncenter size-large wp-image-6770\" \/><\/p>\n<p><\/p>\n<p>Entre los expositores estar\u00e1 nuestro socio <b>MedioDesign<\/b> donde se ver\u00e1 su nueva colecci\u00f3n de piezas \u00fanicas: Objects by Medio. Si desea saber m\u00e1s informaci\u00f3n, puede visitar la <a href=\"http:\/\/objectsbymedio.com\/\">siguiente p\u00e1gina web<\/a>.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre adquisici\u00f3n de entradas y horarios puedes visitar la <a href=\"http:\/\/www.paloaltomarket.com\/es\/inicio\">p\u00e1gina web oficial<\/a> de <b>Palo Alto Market<\/b>. <\/p>\n<p><b>Palo Alto Market<\/b> es un mercado callejero y de calidad que se propone convertirse en una cita mensual imprescindible. El horario es de 11 de la ma\u00f1ana a 9 de la noche y el precio de la entrada: 2 \u20ac. Los menores de 12 a\u00f1os tienen entrada gratuita.<\/p>\n<hr\/>\n<h3>Palo Alto Market<br \/>\nS\u00e1bado 3 Y  Domingo 4 de OCTUBRE<br \/>\nde 11.00h a 21.00h<br \/>\nEntrada: 2\u20ac. Gratuita para menores de 12 a\u00f1os.<\/h3>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El primer fin de semana de los meses Octubre, Noviembre y Diciembre, Palo Alto Market vuelve de nuevo a Barcelona!&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":6771,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[123,122,1266,232,947,1213,1632,945,1508],"class_list":["post-6769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-diseno","tag-disseny","tag-market","tag-mediodesign","tag-mercado","tag-mercat","tag-objects-by-medio","tag-palo-alto-market","tag-street-market"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palo Alto Market torna un altre cop<\/title>\n<meta name=\"description\" content=\"Palo Alto\u00a0Market\u00a0torna un altre cop! Entre els expositors hi haur\u00e0 el nostre associat\u00a0MedioDesign\u00a0on es veur\u00e0 la seva nova col\u00b7lecci\u00f3 de peces \u00faniques\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palo Alto Market torna un altre cop\" \/>\n<meta property=\"og:description\" content=\"Palo Alto\u00a0Market\u00a0torna un altre cop! Entre els expositors hi haur\u00e0 el nostre associat\u00a0MedioDesign\u00a0on es veur\u00e0 la seva nova col\u00b7lecci\u00f3 de peces \u00faniques\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-28T11:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/09\/12047000_970377273020098_6132034629719827883_n.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/palo-alto-market-torna-un-altre-cop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/palo-alto-market-torna-un-altre-cop\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"Palo Alto Market, regreza una vez m\u00e1s\",\"datePublished\":\"2015-09-28T11:02:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/palo-alto-market-torna-un-altre-cop\\\/\"},\"wordCount\":526,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/palo-alto-market-torna-un-altre-cop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25011009\\\/12047000_970377273020098_6132034629719827883_n.jpg\",\"keywords\":[\"Dise\u00f1o\",\"Disseny\",\"market\",\"Mediodesing\",\"mercado\",\"mercat\",\"objects by medio\",\"palo alto market\",\"street market\"],\"articleSection\":[\"Est\u00e1 pasando\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/\",\"name\":\"Palo Alto Market torna un altre cop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/palo-alto-market-torna-un-altre-cop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25011009\\\/12047000_970377273020098_6132034629719827883_n.jpg\",\"datePublished\":\"2015-09-28T11:02:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"Palo Alto\u00a0Market\u00a0torna un altre cop! Entre els expositors hi haur\u00e0 el nostre associat\u00a0MedioDesign\u00a0on es veur\u00e0 la seva nova col\u00b7lecci\u00f3 de peces \u00faniques\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25011009\\\/12047000_970377273020098_6132034629719827883_n.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2015\\\/09\\\/25011009\\\/12047000_970377273020098_6132034629719827883_n.jpg\",\"width\":960,\"height\":352,\"caption\":\"Palo Alto Market, 2 y 4 de octubre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/palo-alto-market-torna-un-altre-cop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palo Alto Market, regreza una vez m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palo Alto Market torna un altre cop","description":"Palo Alto\u00a0Market\u00a0torna un altre cop! Entre els expositors hi haur\u00e0 el nostre associat\u00a0MedioDesign\u00a0on es veur\u00e0 la seva nova col\u00b7lecci\u00f3 de peces \u00faniques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/","og_locale":"es_ES","og_type":"article","og_title":"Palo Alto Market torna un altre cop","og_description":"Palo Alto\u00a0Market\u00a0torna un altre cop! Entre els expositors hi haur\u00e0 el nostre associat\u00a0MedioDesign\u00a0on es veur\u00e0 la seva nova col\u00b7lecci\u00f3 de peces \u00faniques","og_url":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-09-28T11:02:51+00:00","og_image":[{"width":960,"height":352,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/09\/12047000_970377273020098_6132034629719827883_n.png","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/palo-alto-market-torna-un-altre-cop\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/palo-alto-market-torna-un-altre-cop\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"Palo Alto Market, regreza una vez m\u00e1s","datePublished":"2015-09-28T11:02:51+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/palo-alto-market-torna-un-altre-cop\/"},"wordCount":526,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/palo-alto-market-torna-un-altre-cop\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25011009\/12047000_970377273020098_6132034629719827883_n.jpg","keywords":["Dise\u00f1o","Disseny","market","Mediodesing","mercado","mercat","objects by medio","palo alto market","street market"],"articleSection":["Est\u00e1 pasando"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/","url":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/","name":"Palo Alto Market torna un altre cop","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/palo-alto-market-torna-un-altre-cop\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25011009\/12047000_970377273020098_6132034629719827883_n.jpg","datePublished":"2015-09-28T11:02:51+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"Palo Alto\u00a0Market\u00a0torna un altre cop! Entre els expositors hi haur\u00e0 el nostre associat\u00a0MedioDesign\u00a0on es veur\u00e0 la seva nova col\u00b7lecci\u00f3 de peces \u00faniques","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25011009\/12047000_970377273020098_6132034629719827883_n.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2015\/09\/25011009\/12047000_970377273020098_6132034629719827883_n.jpg","width":960,"height":352,"caption":"Palo Alto Market, 2 y 4 de octubre"},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/palo-alto-market-torna-un-altre-cop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"Palo Alto Market, regreza una vez m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=6769"}],"version-history":[{"count":2,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6769\/revisions"}],"predecessor-version":[{"id":6773,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6769\/revisions\/6773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/6771"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=6769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=6769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=6769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}