{"id":6903,"date":"2015-10-14T12:41:41","date_gmt":"2015-10-14T10:41:41","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/es\/?p=6903"},"modified":"2015-10-26T13:27:40","modified_gmt":"2015-10-26T11:27:40","slug":"the-remaining-stains-of-summer-a-addicted-to-life","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/","title":{"rendered":"\u00abThe remaining Stains of Summer\u00bb en Addicted to Life"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_6816\" aria-describedby=\"caption-attachment-6816\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-6816\" src=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-640x494.jpg\" alt=\"last_stains_of_summer_Giacomo_Tonoli_Photographer\" width=\"640\" height=\"494\" srcset=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-640x494.jpg 640w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-600x464.jpg 600w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-180x139.jpg 180w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-620x479.jpg 620w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-768x593.jpg 768w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-1400x1082.jpg 1400w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-1100x850.jpg 1100w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-700x541.jpg 700w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-470x363.jpg 470w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-350x270.jpg 350w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3-430x332.jpg 430w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg 2000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-6816\" class=\"wp-caption-text\">\u00a9 Giacomo Tonoli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<blockquote><p>\u201cMediatizaci\u00f3n: estado de formular y percibir la realidad desde l\u00f3gicas generadas en los medios de comunicaci\u00f3n narrando hip\u00f3tesis concretas a los espectadores. El formato de la mediatizaci\u00f3n puede darse desde series de tv, noticias u otros formatos que construyan discurso sobre un contexto\u201d<\/p><\/blockquote>\n<p><strong><i>Del libro \u201cMundo Consumo\u201d Z. Bauman. Paid\u00f3s 2009<\/i><\/strong><\/p>\n<p><strong>E. Goraieb<\/strong> (Beirut 1960) cumple un objetivo claro mediante su labor art\u00edstica: pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis. Y la tarea no es f\u00e1cil&#8230;<\/p>\n<p>El artista, observa su entorno occidentalizado para ver, desde una mirada cr\u00edtica, las formas que tiene el capitalismo y el sistema Neoliberalista, para des-naturalizar las sociedades contempor\u00e1neas desde el mismo eje: la difusi\u00f3n de la informaci\u00f3n \u201cseleccionada\u201d como \u00fanica fuente de informaci\u00f3n del saber. Esta doctrina regularizada de forma internacional (mediante el fen\u00f3meno \u201cGlobalizaci\u00f3n\u201d, que parece haber pasado de moda, y al que se le daba visibilidad desde de 4 tirados en una plaza), se ha implantado desde nuestra existencia en forma de consumo informativo, de conocimientos que nada tienen que ver con la experiencia y la practica del ser en el mundo (ese fen\u00f3meno anticipado por Heidegger) desde los dispositivos como \u00fanica fuente de aprendizaje ante la existencia.<\/p>\n<p>Este canal \u00fanico de l\u00f3gicas (he de estar comunicado 24 horas al d\u00eda), en el que se ha convertido la vida cotidiana, es el que <strong>Goraieb<\/strong> critica y pone en cuesti\u00f3n a trav\u00e9s de su pr\u00e1ctica. Su trabajo se dirige as\u00ed, en una labor no solo art\u00edstica o reivindicativa mediante un lenguaje creativo, sino en un ejercicio pr\u00e1ctico y personal para desvincularse de un mundo que le reclama una obligatoriedad de flujo de trabajo constante, de supervivencia ante la brutalidad pudiente de lo que supone el triunfo, la econom\u00eda, el s\u00edmbolo social o lo laboral como forma ficticia de triunfo. Esta ultima idea supone aunarse al concepto de la \u201cInconsciencia colectiva\u201d, de la que parece que mucha gente se enorgullezca realizando labores que mas que trabajar para el bienestar social, trabajan para alcanzar una cima ficticia de bienestar propio. <strong>Eric<\/strong> reclama en voz alta un modelo de conciencia, de relaciones, de formas de ver y formas de sentir, y esa actitud es mas que necesaria actualmente, donde se confunden ideas, se glorifican \u00eddolos solo por el hecho ser, ser guapo, planteando un ser humano mas cercano a un brutal animal que a una persona humana.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6812\" aria-describedby=\"caption-attachment-6812\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-6812\" src=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-640x649.jpg\" alt=\"Foto de la obra de Eric Goraieb de Giacomo Tonoli\" width=\"640\" height=\"649\" srcset=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-640x649.jpg 640w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-100x100.jpg 100w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-600x609.jpg 600w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-180x183.jpg 180w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-620x629.jpg 620w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-768x779.jpg 768w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-1400x1420.jpg 1400w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-1100x1116.jpg 1100w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-700x710.jpg 700w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-470x477.jpg 470w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-350x355.jpg 350w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1-423x430.jpg 423w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-1-1.jpg 1972w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-6812\" class=\"wp-caption-text\">\u00a9 Giacomo Tonoli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>No obstante, el ejercicio que realiza <strong>Goraieb<\/strong>, para encontrar su conexi\u00f3n entre su ser y la naturalizaci\u00f3n del mismo como vuelta al origen de la existencia del ser humano, muchas veces queda en un in\u00fatil intento frustrado para hablar de una necesidad que todo ser humano reclama: pensar en si mismo ante el mundo, en las formas de existir y pensar, en las sociedad como colectividad o en el bienestar social, ya que parece ser que el poder que la informaci\u00f3n a la que destinamos diariamente una media de 14 h diarias, se legitima en la sociedad mediante capas de significado que se apoderan de la audiencia y que acaban actuando de una forma des-humanizada, con tal de integrarse en un grupo com\u00fan, con la finalidad de ser aceptado, sin saber el porqu\u00e9. Tan solo para llegar a una hipot\u00e9tico bienestar basado en la imagen y el capital econ\u00f3mico como sin\u00f3nimo de victoria.<\/p>\n<p>Sin embargo, <strong>Goraieb<\/strong>, define muy bien su trabajo desde su pr\u00e1ctica.<\/p>\n<blockquote><p>\u201c-No se trata de realizar arte por el arte, debemos buscar nuevos lenguajes que conjuguen con la actualidad\u201d<\/p><\/blockquote>\n<p><strong>Eric<\/strong>, de esta manera, nos habla de una \u00e9tica y practica personal entorno a una situaci\u00f3n que critica duramente, y a la que decide tomar desde el combate y el sufrimiento que implica su acci\u00f3n pict\u00f3rica, para que los espectadores comprendan su acto art\u00edstico como una reivindicaci\u00f3n a los mas primario del ser humano: la vitalidad, la fuerza, el trazo o la expresi\u00f3n directa del sentimiento. Un ejercicio que permite comunicarnos con lo primigenio del ser, observando desde la contemplaci\u00f3n el entorno, tal y como hace notar en sus \u00faltimos trabajos, <em>Lillies<\/em>, <em>Morning shower<\/em>\u00a0o <em>Rainy day in Shanghai<\/em>\u00a0(2015), donde el artista toma conciencia de su apreciaci\u00f3n por las historias personales y el contexto como escenario de las mismas.<\/p>\n<p>Su trabajo, adem\u00e1s, se perfila desde el campo del arte como una forma reivindicativa de la misma. Trabajos que no se componen desde el lienzo mas tradicional o desde el arte povera como lenguaje: el propio lenguaje del arte es la forma en la que el artista tiene para mostrar su lucha ante el mundo y \u00e9l mismo. Por esa misma raz\u00f3n, las obras se enmarcan como una obra completa: el soporte configura el trabajo tanto como el contenido, y el bastidor pasa de ser un mero soporte para la expresi\u00f3n para convertirse en la expresi\u00f3n en s\u00ed.<\/p>\n<p>Conversar, observar, meditar, relacionarnos y tomar consciencia. Dura tarea a realizar si deseamos crecer personalmente como sujetos mediatizados.<\/p>\n<p><strong>Daniel Gasol<\/strong> de <strong>Oficina36<\/strong>, a dirigido la gesti\u00f3n art\u00edstica de la exposici\u00f3n <em>Remaining stains of summer<\/em>\u00a0y ha redactado el texto.<\/p>\n<p class=\"p1\"><strong>Addicted to Life<\/strong>\u00a0da un giro de 180\u00ba renovando su estructura interna. Con af\u00e1n de ampliar su cartera de servicios, el espacio se ha constituido de un nuevo sistema de paredes m\u00f3viles. Este nuevo sistema va a ofrecer a sus clientes soluciones a la \u201ccarta\u201d en funci\u00f3n de las necesidades de cada evento.<\/p>\n<p class=\"p1\">Este mes de octubre, con la exposici\u00f3n: <i>The remaining stains of <\/i>summer de <i>Eric Goraieb<\/i>, <strong>Addicted to Life<\/strong>\u00a0se inaugura como galerista. Para esta ocasi\u00f3n, se han reconvertido los 350m<sup>2<\/sup> di\u00e1fanos de main room en un multi-espacio segmentado, delimitando distintas \u00e1reas de exposici\u00f3n. Todo ello, gracias al nuevo sistema de paredes m\u00f3viles.<\/p>\n<p><b><a href=\"https:\/\/www.facebook.com\/Addicted-To-Life-Barcelona-593969097372991\/timeline\/\">Addicted to Life<\/a><\/b> es una plataforma creativa experimental que produce y co-produce eventos y proyectos con un denominador com\u00fan: una visi\u00f3n positiva, colaborativa y art\u00edstica. El espacio, una antigua nave rehabilitada del barrio de Poblenou de Barcelona, alberga exposiciones, eventos gastron\u00f3micos, musicales, cinematogr\u00e1ficos, literarios y una tienda-galer\u00eda en la que se pueden adquirir objetos y ropa de segunda mano. Con \u201cThe Remaining Stains of Summer\u201d, Addicted to Life inaugura su actividad como galer\u00eda de arte.<\/p>\n<hr \/>\n<h3>Addicted to Life<\/h3>\n<h3>Carrer de Pujades 156 Bis<\/h3>\n<h3>(+34) 684 337 263<\/h3>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; \u201cMediatizaci\u00f3n: estado de formular y percibir la realidad desde l\u00f3gicas generadas en los medios de comunicaci\u00f3n narrando hip\u00f3tesis&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":6816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1428,848,314,1681,1645,1062,1115,443,1644],"class_list":["post-6903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-addicted-to-life","tag-art","tag-arte","tag-daniel-gasol","tag-eric-goraieb","tag-exhibit","tag-exposicio","tag-exposicion","tag-the-remaining-stains-of-summer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;The remaining Stains of Summer&quot; en Addicted to Life<\/title>\n<meta name=\"description\" content=\"&quot;The remaining Stains of Summer&quot; pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;The remaining Stains of Summer&quot; en Addicted to Life\" \/>\n<meta property=\"og:description\" content=\"&quot;The remaining Stains of Summer&quot; pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-14T10:41:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-26T11:27:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1545\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"\u00abThe remaining Stains of Summer\u00bb en Addicted to Life\",\"datePublished\":\"2015-10-14T10:41:41+00:00\",\"dateModified\":\"2015-10-26T11:27:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/\"},\"wordCount\":3136,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gt-3.jpg\",\"keywords\":[\"addicted to life\",\"art\",\"Arte\",\"daniel gasol\",\"eric goraieb\",\"exhibit\",\"exposici\u00f3\",\"exposici\u00f3n\",\"the remaining stains of summer\"],\"articleSection\":[\"Est\u00e1 pasando\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/\",\"name\":\"\\\"The remaining Stains of Summer\\\" en Addicted to Life\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gt-3.jpg\",\"datePublished\":\"2015-10-14T10:41:41+00:00\",\"dateModified\":\"2015-10-26T11:27:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"\\\"The remaining Stains of Summer\\\" pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#primaryimage\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gt-3.jpg\",\"contentUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gt-3.jpg\",\"width\":2000,\"height\":1545,\"caption\":\"\u00a9 Giacomo Tonoli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/the-remaining-stains-of-summer-a-addicted-to-life\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;The remaining Stains of Summer&#8221; en Addicted to Life\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"The remaining Stains of Summer\" en Addicted to Life","description":"\"The remaining Stains of Summer\" pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/","og_locale":"es_ES","og_type":"article","og_title":"\"The remaining Stains of Summer\" en Addicted to Life","og_description":"\"The remaining Stains of Summer\" pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis","og_url":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-10-14T10:41:41+00:00","article_modified_time":"2015-10-26T11:27:40+00:00","og_image":[{"width":2000,"height":1545,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/the-remaining-stains-of-summer-a-addicted-to-life\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/the-remaining-stains-of-summer-a-addicted-to-life\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"\u00abThe remaining Stains of Summer\u00bb en Addicted to Life","datePublished":"2015-10-14T10:41:41+00:00","dateModified":"2015-10-26T11:27:40+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/the-remaining-stains-of-summer-a-addicted-to-life\/"},"wordCount":3136,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/the-remaining-stains-of-summer-a-addicted-to-life\/#primaryimage"},"thumbnailUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg","keywords":["addicted to life","art","Arte","daniel gasol","eric goraieb","exhibit","exposici\u00f3","exposici\u00f3n","the remaining stains of summer"],"articleSection":["Est\u00e1 pasando"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/","url":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/","name":"\"The remaining Stains of Summer\" en Addicted to Life","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/the-remaining-stains-of-summer-a-addicted-to-life\/#primaryimage"},"thumbnailUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg","datePublished":"2015-10-14T10:41:41+00:00","dateModified":"2015-10-26T11:27:40+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"\"The remaining Stains of Summer\" pretende des-virtualizar el fen\u00f3meno de la informaci\u00f3n de significados desde la contemplaci\u00f3n como forma de an\u00e1lisis","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/#primaryimage","url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg","contentUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/10\/gt-3.jpg","width":2000,"height":1545,"caption":"\u00a9 Giacomo Tonoli"},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/the-remaining-stains-of-summer-a-addicted-to-life\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"&#8220;The remaining Stains of Summer&#8221; en Addicted to Life"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=6903"}],"version-history":[{"count":9,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6903\/revisions"}],"predecessor-version":[{"id":6944,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/6903\/revisions\/6944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/6816"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=6903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=6903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=6903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}