{"id":7424,"date":"2015-12-17T12:39:56","date_gmt":"2015-12-17T10:39:56","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/new\/?p=7424"},"modified":"2015-12-17T12:39:56","modified_gmt":"2015-12-17T10:39:56","slug":"5e-aniversari-la-plataforma","status":"publish","type":"post","link":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/","title":{"rendered":"5\u00ba ANIVERSARIO LA PLATAFORMA"},"content":{"rendered":"<p><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7425\" src=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-640x369.jpg\" alt=\"FOTO A&amp;V (1)\" width=\"640\" height=\"369\" srcset=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-640x369.jpg 640w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-600x346.jpg 600w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-180x104.jpg 180w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-620x358.jpg 620w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-768x443.jpg 768w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-1400x808.jpg 1400w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-1100x635.jpg 1100w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-700x404.jpg 700w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-470x271.jpg 470w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-350x202.jpg 350w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1-430x248.jpg 430w, https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg 1566w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<h1 class=\"p1\"><span class=\"s1\">5\u00ba ANIVERSARIO LA PLATAFORMA<\/span><\/h1>\n<p class=\"p2\"><span class=\"s1\"><strong>La Plataforma<\/strong> galer\u00eda de arte y estudio de producci\u00f3n celebra su quinto aniversario. Para conmemorar una ocasi\u00f3n tan especial, invitamos a todos nuestros artistas, colaboradores y amigos a disfrutar de una noche \u00edntima de m\u00fasica en vivo, arte y gastronom\u00eda. Queremos agradecer el apoyo que han ofrecido al proyecto durante estos cinco a\u00f1os de trayectoria, y nos enorgullece haber trabajado con todos ellos. <\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">Ser\u00e1 una velada para que los visitantes disfruten de <strong>Arte &amp; Venta<\/strong>, una muestra colectiva que re\u00fane arte, libros, objetos y productos gastron\u00f3micos, a la vez que puedan degustar la propuesta de <strong>La Cocina Palpita<\/strong>, cervezas de la mano de <strong>Estrella Damm<\/strong>, y m\u00fasica en directo de <strong>Miguelito Superstar<\/strong>. Un evento que destaca por la compa\u00f1\u00eda acogedora, comida exquisita y buena m\u00fasica. <\/span><\/p>\n<p class=\"p1\"><strong><span class=\"s2\">ARTE<\/span><\/strong><\/p>\n<p class=\"p1\"><span class=\"s1\">Alejandro Armas, <a href=\"https:\/\/www.facebook.com\/amaliacaputod\/\"><span class=\"s2\">Amalia Caputo Studio<\/span><\/a>, Alejandro Tob\u00f3n, Antoni Yranzo, <a href=\"https:\/\/www.facebook.com\/herrarium\/\"><span class=\"s2\">Stefanie Herr<\/span><\/a>, Diego Mallo,<a href=\"https:\/\/www.facebook.com\/asispercales\/\"><span class=\"s2\">Asis Percales Underground<\/span><\/a>, Ricard Aymar, Xavier Rosales Ico, Marina Font, <a href=\"https:\/\/www.facebook.com\/Karenina-Fabrizzi-363203117186189\/\"><span class=\"s2\">Karenina Fabrizzi<\/span><\/a>, Per Henrik Adolfsson, Patrick Thomas, Serena Salvadori, Ramon Paris, Sergio Mora, Ricardo Miras, Rebeca Rodriguez\u00a0y <a href=\"https:\/\/www.facebook.com\/180hilos\/\"><span class=\"s2\">180hilos<\/span><\/a>.<\/span><\/p>\n<p class=\"p1\"><strong><span class=\"s2\">DISE\u00d1O<\/span><\/strong><\/p>\n<p class=\"p1\"><span class=\"s1\">Albert Marti, <a href=\"https:\/\/www.facebook.com\/Aparentment-233149806770255\/\"><span class=\"s2\">Aparentment<\/span><\/a>, Djeco, Isabel Herrera, Javier Blanco, <a href=\"https:\/\/www.facebook.com\/Kikkerland\/\"><span class=\"s2\">Kikkerland Design<\/span><\/a>, Londji, Objetos by Medio, <a href=\"https:\/\/www.facebook.com\/Otto-London-Ponchos-138420676283284\/\"><span class=\"s2\">Otto London Ponchos<\/span><\/a>, Quincalla Zoco y Treee Spirit.<\/span><\/p>\n<p class=\"p1\"><strong><span class=\"s2\">EDITORIALES<\/span><\/strong><\/p>\n<p class=\"p1\"><span class=\"s1\">A buen paso, Ediciones Ekar\u00e9 SUR, Publications for Pleasure,Taschen y The Folio Club\u00a0(socios del Poblenou Urban District).<\/span><\/p>\n<p class=\"p1\"><strong><span class=\"s2\">GASTRONOM\u00cdA<\/span><\/strong><\/p>\n<p class=\"p1\"><span class=\"s1\"><a href=\"https:\/\/www.facebook.com\/LaCocinaPalpita\/\">La Cocina Palpita<\/a>\u00a0(socios del Poblenou Urban District)<\/span><span class=\"s2\">, Las delicias de Papoun, Museu de la Confitura, Nomad Coffe, <a href=\"https:\/\/www.facebook.com\/Rooftop-Smokehouse-204841886388311\/\"><span class=\"s1\">Rooftop Smokehouse<\/span><\/a>, Se\u00f1or Brown el y c\u00f3cteles de <a href=\"https:\/\/www.facebook.com\/mixologymobile\/\"><span class=\"s1\">Mixology Mobile Cocktail Bar<\/span><\/a>.<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\"><span class=\"s2\"><a href=\"http:\/\/lacocinapalpita.com\/\"><b>La Cocina Palpita<\/b><\/a><\/span><span class=\"s1\"> tiene un compromiso con la calidad. Cuidan al m\u00e1ximo cada detalle y hacen de cada proyecto, de cada cliente, algo \u00fanico e irrepetible. Dise\u00f1an el evento y el men\u00fa a medida.<\/span><br \/>\n<\/span><\/p>\n<p class=\"p4\"><span class=\"s2\"><b><a href=\"https:\/\/soundcloud.com\/miguelito-superstar\">Miguelito Superstar<\/a><\/b><\/span><span class=\"s1\">\u00a0es productor y cantante de la Fundaci\u00f3n Tony Manero, y lleva a\u00f1os predicando la palabra del funk dondequiera que vaya. Manero Sound System es uno de los \u00faltimos proyectos de Naci\u00f3n Funk y combina el Dj, la guitarra y la trompeta para revisar, en clave electr\u00f3nica, temas de la Fundaci\u00f3n Tony Manero.<\/span><\/p>\n<p><b><a href=\"https:\/\/www.facebook.com\/La-Plataforma-184571088235180\/timeline\/?ref=hl\">La Plataforma<\/a><\/b>, galer\u00eda de arte y estudio de producci\u00f3n, fue fundada con la intenci\u00f3n de ser un puente entre artistas de distintas disciplinas y pa\u00edses. Como centro de propuestas creativas, goza de un espacio gastron\u00f3mico y es la actual sede del Poblenou Urban District.<span style=\"line-height: 1.5;\">\u00a0<\/span><\/p>\n<hr \/>\n<h3 class=\"p2\">5\u00ba ANIVERSARIO LA PLATAFORMA<\/h3>\n<h3 class=\"p2\"><span class=\"s1\">17.12.2015<\/span><\/h3>\n<h3 class=\"p2\"><span class=\"s1\">19.30H &gt; 22.30H<\/span><\/h3>\n<h3 class=\"p2\"><span class=\"s1\">Carrer de Badajoz 99<\/span><\/h3>\n<p class=\"p2\"><span class=\"s1\">\u00a0<\/span><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 5\u00ba ANIVERSARIO LA PLATAFORMA La Plataforma galer\u00eda de arte y estudio de producci\u00f3n celebra su quinto aniversario. Para&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":7425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[496,314,113,443,21],"class_list":["post-7424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-aniversario","tag-arte","tag-arte-venta","tag-exposicion","tag-la-plataforma"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5\u00e8 Aniversari La Plataforma<\/title>\n<meta name=\"description\" content=\"La Plataforma\u00a0galeria d\u2019art i estudi de producci\u00f3 celebra el seu cinqu\u00e8 aniversari. Per commemorar aquesta ocasi\u00f3 convidem tots els nostres amics\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5\u00e8 Aniversari La Plataforma\" \/>\n<meta property=\"og:description\" content=\"La Plataforma\u00a0galeria d\u2019art i estudi de producci\u00f3 celebra el seu cinqu\u00e8 aniversari. Per commemorar aquesta ocasi\u00f3 convidem tots els nostres amics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-17T10:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1566\" \/>\n\t<meta property=\"og:image:height\" content=\"904\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/5e-aniversari-la-plataforma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/5e-aniversari-la-plataforma\\\/\"},\"author\":{\"name\":\"pnud\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"headline\":\"5\u00ba ANIVERSARIO LA PLATAFORMA\",\"datePublished\":\"2015-12-17T10:39:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/5e-aniversari-la-plataforma\\\/\"},\"wordCount\":1086,\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/5e-aniversari-la-plataforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/FOTO-AV-1.jpg\",\"keywords\":[\"Aniversario\",\"Arte\",\"Arte &amp; Venta\",\"exposici\u00f3n\",\"La Plataforma\"],\"articleSection\":[\"Est\u00e1 pasando\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/\",\"name\":\"5\u00e8 Aniversari La Plataforma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/5e-aniversari-la-plataforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/FOTO-AV-1.jpg\",\"datePublished\":\"2015-12-17T10:39:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\"},\"description\":\"La Plataforma\u00a0galeria d\u2019art i estudi de producci\u00f3 celebra el seu cinqu\u00e8 aniversari. Per commemorar aquesta ocasi\u00f3 convidem tots els nostres amics\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/FOTO-AV-1.jpg\",\"contentUrl\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/FOTO-AV-1.jpg\",\"width\":1566,\"height\":904},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/5e-aniversari-la-plataforma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5\u00ba ANIVERSARIO LA PLATAFORMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/#\\\/schema\\\/person\\\/980a2cf34b399d5218205730acd54a7e\",\"name\":\"pnud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g\",\"caption\":\"pnud\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5\u00e8 Aniversari La Plataforma","description":"La Plataforma\u00a0galeria d\u2019art i estudi de producci\u00f3 celebra el seu cinqu\u00e8 aniversari. Per commemorar aquesta ocasi\u00f3 convidem tots els nostres amics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/","og_locale":"es_ES","og_type":"article","og_title":"5\u00e8 Aniversari La Plataforma","og_description":"La Plataforma\u00a0galeria d\u2019art i estudi de producci\u00f3 celebra el seu cinqu\u00e8 aniversari. Per commemorar aquesta ocasi\u00f3 convidem tots els nostres amics","og_url":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/","og_site_name":"Poblenou Urban District","article_published_time":"2015-12-17T10:39:56+00:00","og_image":[{"width":1566,"height":904,"url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg","type":"image\/jpeg"}],"author":"pnud","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pnud","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poblenouurbandistrict.com\/5e-aniversari-la-plataforma\/#article","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/5e-aniversari-la-plataforma\/"},"author":{"name":"pnud","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"headline":"5\u00ba ANIVERSARIO LA PLATAFORMA","datePublished":"2015-12-17T10:39:56+00:00","mainEntityOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/5e-aniversari-la-plataforma\/"},"wordCount":1086,"image":{"@id":"https:\/\/poblenouurbandistrict.com\/5e-aniversari-la-plataforma\/#primaryimage"},"thumbnailUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg","keywords":["Aniversario","Arte","Arte &amp; Venta","exposici\u00f3n","La Plataforma"],"articleSection":["Est\u00e1 pasando"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/","url":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/","name":"5\u00e8 Aniversari La Plataforma","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/5e-aniversari-la-plataforma\/#primaryimage"},"thumbnailUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg","datePublished":"2015-12-17T10:39:56+00:00","author":{"@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e"},"description":"La Plataforma\u00a0galeria d\u2019art i estudi de producci\u00f3 celebra el seu cinqu\u00e8 aniversari. Per commemorar aquesta ocasi\u00f3 convidem tots els nostres amics","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/#primaryimage","url":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg","contentUrl":"https:\/\/poblenouurbandistrict.com\/wp-content\/uploads\/2015\/12\/FOTO-AV-1.jpg","width":1566,"height":904},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/5e-aniversari-la-plataforma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"5\u00ba ANIVERSARIO LA PLATAFORMA"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/poblenouurbandistrict.com\/#\/schema\/person\/980a2cf34b399d5218205730acd54a7e","name":"pnud","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67146597b405ee077a24e519f75c3e2031736596d6ce35af3a34c122c93d0d7b?s=96&d=retro&r=g","caption":"pnud"}}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/7424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/comments?post=7424"}],"version-history":[{"count":3,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/7424\/revisions"}],"predecessor-version":[{"id":7428,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/posts\/7424\/revisions\/7428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/7425"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=7424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/categories?post=7424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=7424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}