{"id":10003179,"date":"2022-04-21T18:20:15","date_gmt":"2022-04-21T16:20:15","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?post_type=tribe_events&#038;p=29167"},"modified":"2022-04-21T18:20:15","modified_gmt":"2022-04-21T16:20:15","slug":"exposicio-ocells-de-ciutat","status":"publish","type":"tribe_events","link":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/","title":{"rendered":"Exposici\u00f3n: P\u00e1jaros de ciudad"},"content":{"rendered":"<p><\/p>\n<p class=\"font_8\">Esta exposici\u00f3n pretende ofrecer una aproximaci\u00f3n a algunos de los p\u00e1jaros m\u00e1s comunes e interesantes de la ciudad de Barcelona.<\/p>\n<p class=\"font_8\">Mediante la combinaci\u00f3n de texto, pintura y escultura, la artista Cristina Carbone nos invita a valorar el patrimonio natural de la ciudad y, por tanto, a avanzar en la consecuci\u00f3n de los objetivos de la conservaci\u00f3n de la biodiversidad dentro de ella.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Esta exposici\u00f3n pretende ofrecer una aproximaci\u00f3n a algunos de los p\u00e1jaros m\u00e1s comunes e interesantes de la ciudad de Barcelona&#8230;. <a href=\"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":29168,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10003179","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3n: P\u00e1jaros de ciudad &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3n: P\u00e1jaros de ciudad &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"Esta exposici\u00f3n pretende ofrecer una aproximaci\u00f3n a algunos de los p\u00e1jaros m\u00e1s comunes e interesantes de la ciudad de Barcelona.... M\u00e1s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050515\/pud-agenda-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/\",\"name\":\"Exposici\u00f3n: P\u00e1jaros de ciudad &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/04\\\/25050515\\\/pud-agenda-7.jpg\",\"datePublished\":\"2022-04-21T16:20:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/04\\\/25050515\\\/pud-agenda-7.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/04\\\/25050515\\\/pud-agenda-7.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-ocells-de-ciutat\\\/2022-04-26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exposici\u00f3n: P\u00e1jaros de ciudad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n: P\u00e1jaros de ciudad &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/","og_locale":"es_ES","og_type":"article","og_title":"Exposici\u00f3n: P\u00e1jaros de ciudad &#8211; Poblenou Urban District","og_description":"Esta exposici\u00f3n pretende ofrecer una aproximaci\u00f3n a algunos de los p\u00e1jaros m\u00e1s comunes e interesantes de la ciudad de Barcelona.... M\u00e1s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/","og_site_name":"Poblenou Urban District","og_image":[{"width":1000,"height":1000,"url":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050515\/pud-agenda-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/","url":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/","name":"Exposici\u00f3n: P\u00e1jaros de ciudad &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050515\/pud-agenda-7.jpg","datePublished":"2022-04-21T16:20:15+00:00","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050515\/pud-agenda-7.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/04\/25050515\/pud-agenda-7.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-ocells-de-ciutat\/2022-04-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/"},{"@type":"ListItem","position":3,"name":"Exposici\u00f3n: P\u00e1jaros de ciudad"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events\/10003179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events\/10003179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/29168"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=10003179"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=10003179"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10003179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}