{"id":10003308,"date":"2022-05-04T15:50:09","date_gmt":"2022-05-04T13:50:09","guid":{"rendered":"https:\/\/poblenouurbandistrict.com\/?post_type=tribe_events&#038;p=29786"},"modified":"2022-05-04T15:50:09","modified_gmt":"2022-05-04T13:50:09","slug":"exposicio-construcciones-analogicas","status":"publish","type":"tribe_events","link":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/","title":{"rendered":"Exposici\u00f3n: Construcciones Anal\u00f3gicas"},"content":{"rendered":"<p>El pr\u00f3ximo 7 de mayo, La Plataforma inaugura \u201cConstrucciones Anal\u00f3gicas\u201d, una colaboraci\u00f3n entre los artistas Paul Ekaitz y Jos\u00e9 Herna\u0301ndez-Diez que rescata en el momento exacto ideas brillantes de ambos artistas y representa la oportunidad perfecta para crear un \u201ccad\u00e1ver exquisito\u00bb, porque nunca es tarde para impregnar con nostalgia punk la fascinaci\u00f3n por el fuego, la luz y la persistencia de la imagen.<\/p>\n<p>Disponible hasta el 5 de junio.<\/p>","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 7 de mayo, La Plataforma inaugura \u201cConstrucciones Anal\u00f3gicas\u201d, una colaboraci\u00f3n entre los artistas Paul Ekaitz y Jos\u00e9 Herna\u0301ndez-Diez&#8230; <a href=\"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/\">M\u00e1s  \u2192<\/a><\/p>\n","protected":false},"author":5,"featured_media":29788,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[3564,3553],"class_list":["post-10003308","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-art","tribe_events_cat-exposicion","cat_art","cat_exposicion","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3n: Construcciones Anal\u00f3gicas &#8211; Poblenou Urban District<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3n: Construcciones Anal\u00f3gicas &#8211; Poblenou Urban District\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 7 de mayo, La Plataforma inaugura \u201cConstrucciones Anal\u00f3gicas\u201d, una colaboraci\u00f3n entre los artistas Paul Ekaitz y Jos\u00e9 Herna\u0301ndez-Diez... M\u00e1s \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/\" \/>\n<meta property=\"og:site_name\" content=\"Poblenou Urban District\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.poblenouurbandistrict.com\/2022\/05\/25051114\/279358461-688309769053963-6023891661999423393-n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1689\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/\",\"name\":\"Exposici\u00f3n: Construcciones Anal\u00f3gicas &#8211; Poblenou Urban District\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/05\\\/25051114\\\/279358461-688309769053963-6023891661999423393-n.jpg\",\"datePublished\":\"2022-05-04T13:50:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/05\\\/25051114\\\/279358461-688309769053963-6023891661999423393-n.jpg\",\"contentUrl\":\"https:\\\/\\\/media.poblenouurbandistrict.com\\\/2022\\\/05\\\/25051114\\\/279358461-688309769053963-6023891661999423393-n.jpg\",\"width\":1440,\"height\":1689},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/exposicio-construcciones-analogicas\\\/2022-05-17\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exposici\u00f3n: Construcciones Anal\u00f3gicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/\",\"name\":\"Poblenou Urban District\",\"description\":\"Comunidad Creativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poblenouurbandistrict.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n: Construcciones Anal\u00f3gicas &#8211; Poblenou Urban District","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/","og_locale":"es_ES","og_type":"article","og_title":"Exposici\u00f3n: Construcciones Anal\u00f3gicas &#8211; Poblenou Urban District","og_description":"El pr\u00f3ximo 7 de mayo, La Plataforma inaugura \u201cConstrucciones Anal\u00f3gicas\u201d, una colaboraci\u00f3n entre los artistas Paul Ekaitz y Jos\u00e9 Herna\u0301ndez-Diez... M\u00e1s \u2192","og_url":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/","og_site_name":"Poblenou Urban District","og_image":[{"width":1440,"height":1689,"url":"https:\/\/media.poblenouurbandistrict.com\/2022\/05\/25051114\/279358461-688309769053963-6023891661999423393-n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/","url":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/","name":"Exposici\u00f3n: Construcciones Anal\u00f3gicas &#8211; Poblenou Urban District","isPartOf":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/#primaryimage"},"image":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/#primaryimage"},"thumbnailUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/05\/25051114\/279358461-688309769053963-6023891661999423393-n.jpg","datePublished":"2022-05-04T13:50:09+00:00","breadcrumb":{"@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/#primaryimage","url":"https:\/\/media.poblenouurbandistrict.com\/2022\/05\/25051114\/279358461-688309769053963-6023891661999423393-n.jpg","contentUrl":"https:\/\/media.poblenouurbandistrict.com\/2022\/05\/25051114\/279358461-688309769053963-6023891661999423393-n.jpg","width":1440,"height":1689},{"@type":"BreadcrumbList","@id":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/exposicio-construcciones-analogicas\/2022-05-17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poblenouurbandistrict.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/poblenouurbandistrict.com\/es\/agenda\/"},{"@type":"ListItem","position":3,"name":"Exposici\u00f3n: Construcciones Anal\u00f3gicas"}]},{"@type":"WebSite","@id":"https:\/\/poblenouurbandistrict.com\/es\/#website","url":"https:\/\/poblenouurbandistrict.com\/es\/","name":"Poblenou Urban District","description":"Comunidad Creativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poblenouurbandistrict.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events\/10003308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events\/10003308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media\/29788"}],"wp:attachment":[{"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/media?parent=10003308"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tags?post=10003308"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/poblenouurbandistrict.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10003308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}